{"id":9855,"date":"2021-12-20T16:31:44","date_gmt":"2021-12-20T19:31:44","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=9855"},"modified":"2021-12-20T16:32:15","modified_gmt":"2021-12-20T19:32:15","slug":"stf-define-inconstitucionalidade-sobre-aliquotas-de-icms-que-impacta-na-conta-de-luz","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/stf-define-inconstitucionalidade-sobre-aliquotas-de-icms-que-impacta-na-conta-de-luz\/","title":{"rendered":"STF define inconstitucionalidade sobre al\u00edquotas de ICMS que impacta na conta de luz"},"content":{"rendered":"<h4><strong>STF define inconstitucionalidade sobre al\u00edquotas de ICMS que impacta na conta de luz<\/strong><\/h4>\n<h5>Empres\u00e1rios devem avaliar a realidade tribut\u00e1ria da empresa e podem questionar a al\u00edquota na justi\u00e7a<\/h5>\n<p>02\/12\/2021 \u00e0s 15h34min &#8211; Atualizada em 02\/12\/2021 \u00e0s 19h40min<\/p>\n<p>Confira mat\u00e9ria no link: <a href=\"https:\/\/abnoticianews.com.br\/noticia\/60195\/stf-define-inconstitucionalidade-sobre-aliquotas-de-icms-que-impacta-na-conta-de-luz\">https:\/\/abnoticianews.com.br\/noticia\/60195\/stf-define-inconstitucionalidade-sobre-aliquotas-de-icms-que-impacta-na-conta-de-luz<\/a><\/p>\n<div id=\"attachment_9856\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9856\" class=\"size-medium wp-image-9856\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-300x177.jpg\" alt=\"\" width=\"300\" height=\"177\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-300x177.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-800x471.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-768x452.jpg 768w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-248x146.jpg 248w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-50x29.jpg 50w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg-127x75.jpg 127w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/02123612_calculator.jpg.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-9856\" class=\"wp-caption-text\">Imagem: Pixabey<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>A decis\u00e3o do Supremo Tribunal Federal (STF) em considerar inconstitucional a Lei estadual que determina al\u00edquotas de ICMS para servi\u00e7os de energia el\u00e9trica e telecomunica\u00e7\u00f5es superiores \u00e0 m\u00e9dia geral \u00e9 um precedente a um debate amplo sobre a redu\u00e7\u00e3o do imposto. Numa m\u00e9dia nacional, a al\u00edquota de ICMS para energia el\u00e9trica e telecomunica\u00e7\u00f5es \u00e9 de 25%, extrapolando a m\u00e9dia geral dos outros bens. Se aplicado o entendimento do Supremo, deveria ser igualada \u00e0 al\u00edquota geral de 18%.<br \/>\n\u201cNessa premissa, frente ao posicionamento favor\u00e1vel do corte, o empres\u00e1rio deve avaliar a realidade tribut\u00e1ria de sua empresa e questionar perante o Judici\u00e1rio a inconstitucionalidade da al\u00edquota do ICMS para os servi\u00e7os\u201d, analisa o advogado Lucas Ciappina, especialista em Direito Tribut\u00e1rio do escrit\u00f3rio Balera, Berbel &amp; Mitne Advogados.<br \/>\nTecnicamente, o ICMS deve respeitar o princ\u00edpio da seletividade em fun\u00e7\u00e3o da essencialidade das mercadorias e servi\u00e7os, isto \u00e9, o tributo dever\u00e1 ter al\u00edquotas favorecidas em raz\u00e3o da essencialidade do bem dispon\u00edvel. Ao colocar na energia el\u00e9trica uma al\u00edquota superior comparada \u00e0 de outros bens n\u00e3o essenciais, tais como armas e bebidas alco\u00f3licas, o STF entendeu ser inconstitucional o valor majorado.<br \/>\nA decis\u00e3o foi tomada no \u00faltimo dia 22, diante de Mandado de Seguran\u00e7a impetrado por uma rede varejista que contestou a al\u00edquota de 25% no ICMS de servi\u00e7os de energia el\u00e9trica e telecomunica\u00e7\u00f5es de consumidores de grande porte no estado de Santa Catarina, frente \u00e0 al\u00edquota geral para outros setores que \u00e9 de 17%. A empresa destacou que a al\u00edquota de 25% do estado \u00e9 desproporcional e percentualmente superior a outros bens n\u00e3o essenciais como cosm\u00e9ticos, armas, bebidas alco\u00f3licas e fumo.<br \/>\nA decis\u00e3o abre precedente favor\u00e1vel para discuss\u00e3o semelhante em outros estados, inclusive a pr\u00f3pria varejista tem a\u00e7\u00f5es em outros 22 estados e Distrito Federal questionando al\u00edquotas. O resultado do julgamento, no entanto, tem limites. \u201cPor se tratar de um recurso extraordin\u00e1rio, a decis\u00e3o n\u00e3o tem for\u00e7as para derrubar a lei catarinense e ter\u00e1 apenas efeitos entre as partes. Contudo, em raz\u00e3o de ter repercuss\u00e3o geral, vincula demais decis\u00f5es do Poder Judici\u00e1rio\u201d, aponta o advogado Bruno Fazzolo, do time do Balera, Berbel &amp; Mitne Advogados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>STF define inconstitucionalidade sobre al\u00edquotas de ICMS que impacta na conta de luz Empres\u00e1rios devem avaliar a realidade tribut\u00e1ria da empresa e podem questionar a al\u00edquota<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":9766,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[160],"tags":[],"class_list":["post-9855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vilela-berbel-e-mitne"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=9855"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/9766"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=9855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=9855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=9855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}