{"id":9775,"date":"2021-12-14T16:08:05","date_gmt":"2021-12-14T19:08:05","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=9775"},"modified":"2021-12-14T16:08:05","modified_gmt":"2021-12-14T19:08:05","slug":"mt-apresenta-risco-alto-para-epidemia-e-surto-de-dengue-2","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/mt-apresenta-risco-alto-para-epidemia-e-surto-de-dengue-2\/","title":{"rendered":"MT apresenta risco alto para epidemia e surto de Dengue"},"content":{"rendered":"<h4 class=\"entry-title titulo-post\">MT apresenta risco alto para epidemia e surto de Dengue<\/h4>\n<p><a class=\"entry-date published\">11 DE NOVEMBRO DE 2021 &#8211; 11:19<\/a><\/p>\n<p>Confira mat\u00e9ria no link: https:\/\/matogrossomais.com.br\/2021\/11\/11\/mato-grosso-apresenta-risco-alto-para-nova-epidemia-e-surto-de-dengue\/<\/p>\n<div id=\"attachment_9776\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9776\" class=\"size-medium wp-image-9776\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-300x218.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-800x582.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-768x559.jpg 768w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-201x146.jpg 201w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-50x36.jpg 50w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630-103x75.jpg 103w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/mosquito-da-dengue-e1499197068630.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-9776\" class=\"wp-caption-text\">Divulga\u00e7\u00e3o<\/p><\/div>\n<div>\n<p>Antes mesmo da chegada do ver\u00e3o, per\u00edodo em que as doen\u00e7as provocadas pelo\u00a0Aedes aegypti\u00a0atingem seu \u00e1pice, o Mato Grosso j\u00e1 apresenta \u00edndices preocupantes. Segundo dados at\u00e9 o dia 23 de outubro, j\u00e1 foram notificados 24.967 casos no estado, sendo que foram 28 graves e seis mortes confirmadas, al\u00e9m de outras tr\u00eas em investiga\u00e7\u00e3o. A incid\u00eancia \u00e9 de 716,5 para cada 100 mil habitantes. Vale lembrar que, por causa da pandemia da Covid-19, todos os estados apresentam subnotifica\u00e7\u00e3o para as arboviroses devido a uma baixa procura pelos hospitais. Mesmo assim, o Centro-Oeste \u00e9 a regi\u00e3o que apresenta a maior taxa de incid\u00eancia de dengue no pa\u00eds este ano.<\/p>\n<\/div>\n<div>\n<p>Com o in\u00edcio da temporada das chuvas, o perigo da multiplica\u00e7\u00e3o dos\u00a0Aedes aegypti\u00a0\u00e9 enorme. Isso porque, ap\u00f3s aproximadamente 15h da postura, os ovos dos mosquitos conseguem resistir a longos per\u00edodos de baixa umidade, podendo ficar at\u00e9 450 dias no seco.<\/p>\n<\/div>\n<div>\n<p>Campanhas de conscientiza\u00e7\u00e3o e aspers\u00e3o de veneno s\u00e3o os caminhos b\u00e1sicos, mas sem resultados permanentes a curto prazo. Pesquisas com material gen\u00e9tico e estudo do ambiente s\u00e3o algumas alternativas. A biotecnologia j\u00e1 tem respostas assertivas, comprovadas e sem agredir o ambiente ou expor a comunidade a riscos.<\/p>\n<\/div>\n<div>O Projeto Controle Natural de Vetores, desenvolvido pela Forrest Brasil Tecnologia, com o trabalho de cientistas brasileiros e israelenses, se mostrou eficiente. Em Ortigueira (PR), numa parceria com a empresa Klabin e o munic\u00edpio, a a\u00e7\u00e3o j\u00e1 comprovou seus melhores resultados no Paran\u00e1. Implantado em novembro de 2020, em seis meses, a redu\u00e7\u00e3o foi de 92% da popula\u00e7\u00e3o local de mosquitos. O n\u00famero de pessoas doentes tamb\u00e9m caiu, de 120 para 4, quase 97%. N\u00e3o foram registradas mortes.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MT apresenta risco alto para epidemia e surto de Dengue 11 DE NOVEMBRO DE 2021 &#8211; 11:19 Confira mat\u00e9ria no link: https:\/\/matogrossomais.com.br\/2021\/11\/11\/mato-grosso-apresenta-risco-alto-para-nova-epidemia-e-surto-de-dengue\/ Antes mesmo da chegada<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":9777,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[236],"tags":[],"class_list":["post-9775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forrest"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=9775"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/9777"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=9775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=9775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=9775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}