{"id":9745,"date":"2021-12-14T14:20:06","date_gmt":"2021-12-14T17:20:06","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=9745"},"modified":"2021-12-14T14:28:43","modified_gmt":"2021-12-14T17:28:43","slug":"biotecnologia-brasileira-sustentavel-reduz-em-99-o-mosquito-da-dengue","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/biotecnologia-brasileira-sustentavel-reduz-em-99-o-mosquito-da-dengue\/","title":{"rendered":"Biotecnologia Brasileira Sustent\u00e1vel Reduz em 99% o Mosquito da Dengue"},"content":{"rendered":"<h4>Biotecnologia Brasileira Sustent\u00e1vel Reduz em 99% o Mosquito da Dengue<\/h4>\n<p class=\"lead\">Forrest do Brasil utiliza mosquitos est\u00e9reis, n\u00e3o transg\u00eanicos, em controle natural<\/p>\n<p class=\"autor\">REDA\u00c7\u00c3O\u00a0PUBLICADO EM 12\/12\/2021, \u00c0S 10H06<\/p>\n<p>&nbsp;<\/p>\n<p>Confira a mat\u00e9ria no link: https:\/\/aventurasnahistoria.uol.com.br\/noticias\/historia-hoje\/biotecnologia-brasileira-sustentavel-reduz-em-99-o-mosquito-da-dengue.phtml<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9750\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg-300x169.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg-768x432.jpg 768w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg-260x146.jpg 260w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg-50x28.jpg 50w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg-133x75.jpg 133w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/12\/dengeyeu_widelg.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Em 2021, al\u00e9m do enfrentamento\u00a0<a href=\"https:\/\/aventurasnahistoria.uol.com.br\/noticias\/historia-hoje\/cidade-chinesa-ira-recompensar-resultados-positivo-de-covid-19.phtml\">da Covid-19,<\/a>\u00a0o estado de S\u00e3o Paulo se confrontou com uma grave epidemia de Dengue. A secretaria estadual de Sa\u00fade computou, at\u00e9 outubro, 323.041 casos notificados.<\/p>\n<p>Al\u00e9m da capital que viu os casos da\u00a0<a href=\"https:\/\/aventurasnahistoria.uol.com.br\/noticias\/historia-hoje\/austriaco-que-pegou-covid-de-proposito-para-evitar-vacina-morre-da-doenca.phtml\">doen\u00e7a<\/a>\u00a0aumentarem em 253% este ano, outros grandes munic\u00edpios enfrentam situa\u00e7\u00e3o cr\u00edtica: S\u00e3o Jos\u00e9 do Rio Preto (31.101), Tatu\u00ed (26.042), Santos (14.014) e Piracicaba (13.765). Somente\u00a0<a href=\"https:\/\/aventurasnahistoria.uol.com.br\/noticias\/historia-hoje\/governo-jamaicano-defende-producao-de-maconha-em-campanha.phtml\">campanhas<\/a>\u00a0de conscientiza\u00e7\u00e3o e a aspers\u00e3o de fumac\u00ea j\u00e1 demonstraram que n\u00e3o s\u00e3o suficientes.<\/p>\n<p>H\u00e1 novas tecnologias em curso para o combate \u00e0s arboviroses provocadas pelo Aedes aegypti. Mas quantas delas s\u00e3o sustent\u00e1veis e n\u00e3o envolvem a pr\u00f3pria popula\u00e7\u00e3o?<\/p>\n<p>O Projeto Controle Natural de Vetores desenvolvido pela Forrest Brasil Tecnologia, com trabalho de cientistas brasileiros e israelenses, apresenta excelentes resultados.<\/p>\n<p>A empresa \u00e9 uma multinacional de biotecnologia avan\u00e7ada que busca solu\u00e7\u00f5es para combater os mosquitos vetores de pat\u00f3genos causadores de doen\u00e7as de grande impacto para a sa\u00fade p\u00fablica.<\/p>\n<p>O m\u00e9todo \u00e9 baseado na tecnologia TIE &#8211; utiliza\u00e7\u00e3o do Inseto Est\u00e9ril -, em que os mosquitos s\u00e3o soltos de forma massiva. Os machos est\u00e9reis se acasalam com as f\u00eameas selvagens, que deixam de procriar, o que provoca uma imediata redu\u00e7\u00e3o na infesta\u00e7\u00e3o do mosquito e dissemina\u00e7\u00e3o de doen\u00e7as como a Dengue, Chikungunya, Zika e Febre Amarela.<\/p>\n<div class=\"d-flex justify-content-center my-3\">\n<div id=\"banner-300x250-2-area\" data-desktop=\"300x250\" data-mobile=\"320x50\"><\/div>\n<\/div>\n<p>O estudo \u00e9 reconhecido pela comunidade cient\u00edfica internacional e foi publicado no Journal of Infectious Diseases, revista m\u00e9dica revisada por pares, editada pela Oxford University Press em nome da Sociedade de Doen\u00e7as Infecciosas da Am\u00e9rica, principal refer\u00eancia na \u00e1rea.<\/p>\n<p>A Secretaria de Sa\u00fade do Paran\u00e1 tamb\u00e9m reconhece e aprova a tecnologia. E os resultados j\u00e1 s\u00e3o vistos. A mais recente utiliza\u00e7\u00e3o do m\u00e9todo acontece na cidade de Ortigueira (PR).<\/p>\n<p>O trabalho \u00e9 realizado em parceria com a empresa Klabin e o munic\u00edpio foi implantado em novembro de 2020. Em um ano a redu\u00e7\u00e3o foi de 99% no n\u00famero de larvas vi\u00e1veis encontradas em campo.<\/p>\n<div class=\"d-flex justify-content-center my-3\">\n<div id=\"banner-300x250-3-area\" data-desktop=\"300x250\" data-mobile=\"320x50\"><\/div>\n<\/div>\n<p>Dados mais recentes mostram que a continuidade do trabalho fez com que, h\u00e1 dois meses, n\u00e3o fossem mais encontrados ovos e larvas na regi\u00e3o. O n\u00famero de pessoas doentes tamb\u00e9m caiu, de 120 para 5, quase 95%. N\u00e3o foram registradas mortes.<\/p>\n<p>&#8220;Neste momento de mudan\u00e7as na din\u00e2mica populacional, utilizar tecnologia e inova\u00e7\u00e3o \u00e9 fundamental, pois as medidas de controle utilizadas atualmente s\u00e3o de certa forma pouco efetivas e de alto custo com baixo poder de preven\u00e7\u00e3o&#8221;, explica a epidemiologista Daniele Queiroz, coordenadora da Forrest, consultora da OPAS (Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade), com especializa\u00e7\u00e3o na Universidade Johns Hopkins, nos EUA.<\/p>\n<p>Com o in\u00edcio da temporada das chuvas, o perigo da multiplica\u00e7\u00e3o dos\u00a0Aedes aegypti\u00a0\u00e9 enorme. Isso porque, ap\u00f3s aproximadamente 15h da postura, os ovos dos mosquitos conseguem resistir a longos per\u00edodos de baixa umidade, podendo ficar at\u00e9 450 dias no seco.<\/p>\n<div class=\"d-flex justify-content-center my-3\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Biotecnologia Brasileira Sustent\u00e1vel Reduz em 99% o Mosquito da Dengue Forrest do Brasil utiliza mosquitos est\u00e9reis, n\u00e3o transg\u00eanicos, em controle natural REDA\u00c7\u00c3O\u00a0PUBLICADO EM 12\/12\/2021, \u00c0S 10H06<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":9746,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[236],"tags":[],"class_list":["post-9745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forrest"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=9745"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/9746"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=9745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=9745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=9745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}