{"id":9563,"date":"2021-11-12T08:29:48","date_gmt":"2021-11-12T11:29:48","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=9563"},"modified":"2021-11-17T08:34:34","modified_gmt":"2021-11-17T11:34:34","slug":"rio-grande-da-serra-e-unica-cidade-sem-combate-a-dengue","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/rio-grande-da-serra-e-unica-cidade-sem-combate-a-dengue\/","title":{"rendered":"Rio Grande da Serra \u00e9 \u00fanica cidade sem combate \u00e0 dengue\u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-9564\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/11\/Diario-do-Grande-ABC.jpg\" alt=\"\" width=\"318\" height=\"212\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/11\/Diario-do-Grande-ABC.jpg 195w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/11\/Diario-do-Grande-ABC-50x33.jpg 50w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/11\/Diario-do-Grande-ABC-113x75.jpg 113w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><a href=\"https:\/\/www.dgabc.com.br\/Editoria\/1\/Setecidades\">Setecidades<\/a><\/h2>\n<p>setecidades@dgabc.com.br | 4435-8319<\/p>\n<p><strong>Rio Grande da Serra \u00e9 \u00fanica cidade sem combate \u00e0 dengue\u00a0<\/strong><\/p>\n<p>Prefeitura alega que Covid levou \u00e0 reestrutura\u00e7\u00e3o na Sa\u00fade; Santo Andr\u00e9, S\u00e3o Bernardo, Diadema e Ribeir\u00e3o Pires registram aumento de casos<\/p>\n<p><strong>Arthur Gandini<\/strong><strong><br \/>\nEspecial para o Di\u00e1rio<\/strong><\/p>\n<p>12\/11\/2021 | 00:01<\/p>\n<p>Rio Grande da Serra \u00e9 a \u00fanica cidade do Grande ABC sem a\u00e7\u00f5es organizadas de preven\u00e7\u00e3o \u00e0 dissemina\u00e7\u00e3o do mosquito Aedes Aegypti. Ser\u00e1 comemorado, no dia 19, o Dia Nacional de Combate \u00e0 Dengue. Em nota, a administra\u00e7\u00e3o informou \u201cque todos os esfor\u00e7os do munic\u00edpio foram voltados para combater a pandemia de Covid-19. Por essa raz\u00e3o, a pasta est\u00e1 reestruturando as a\u00e7\u00f5es de combate\u201d. A Prefeitura afirma que n\u00e3o foram registrados casos de dengue no m\u00eas passado, assim como em outubro de 2020.<\/p>\n<p>O\u00a0<strong>Di\u00e1rio<\/strong>\u00a0questionou as administra\u00e7\u00f5es das demais cidades da regi\u00e3o sobre a incid\u00eancia da doen\u00e7a e a\u00e7\u00f5es de combate \u00e0 dengue. Santo Andr\u00e9, S\u00e3o Bernardo, Diadema e Ribeir\u00e3o Pires registraram aumento do n\u00famero de casos.<br \/>\nEm Santo Andr\u00e9, de janeiro de 2020 em compara\u00e7\u00e3o com o mesmo per\u00edodo deste ano, o total subiu de 40 para 110. Em S\u00e3o Bernardo, o n\u00famero aumentou de 69 para 212 casos. Em Diadema, o registro saltou de 20 para 213 confirma\u00e7\u00f5es. S\u00e3o Caetano informou que em outubro de 2020 n\u00e3o foi registrado nenhum caso. J\u00e1 em outubro deste ano h\u00e1 um caso a ser confirmado. A Prefeitura de Mau\u00e1 n\u00e3o forneceu dados.<\/p>\n<p>A administra\u00e7\u00e3o de Santo Andr\u00e9 conduz semana de mobiliza\u00e7\u00e3o contra a dengue. Ontem e na quarta-feira, por exemplo, foram realizadas a\u00e7\u00f5es educativas em escolas e comunidades. O cal\u00e7ad\u00e3o da Rua Coronel Oliveira Lima vai contar hoje com uma tenda com profissionais da vigil\u00e2ncia. Os andreenses que passarem pelo local ter\u00e3o a oportunidade de aprender medidas de preven\u00e7\u00e3o, sintomas caracter\u00edsticos das doen\u00e7as e o ciclo evolutivo do mosquito. J\u00e1 em S\u00e3o Bernardo, no dia 27, o estacionamento superior do Gin\u00e1sio Poliesportivo da Avenida Kennedy ser\u00e1 palco de a\u00e7\u00f5es de conscientiza\u00e7\u00e3o.<\/p>\n<p>S\u00e3o Caetano, por sua vez, tem promovido campanha informativa nas redes sociais. Agentes p\u00fablicos t\u00eam buscado e eliminado criadouros do mosquito na cidade, al\u00e9m de retirar res\u00edduos em via p\u00fablica que possam acumular \u00e1gua. A administra\u00e7\u00e3o afirma que escolas municipais contaram com palestras sobre o tema. A Prefeitura de Diadema afirma que prepara campanha municipal de intensifica\u00e7\u00e3o das a\u00e7\u00f5es de combate, ressaltou a\u00e7\u00f5es educativas nesta semana em unidades de sa\u00fade e escolas municipais, al\u00e9m das visitas em casas de moradores por agentes de fiscaliza\u00e7\u00e3o.<\/p>\n<p>PUBLICIDADE<\/p>\n<p>Mau\u00e1 tamb\u00e9m refor\u00e7ou a fiscaliza\u00e7\u00e3o das resid\u00eancias, o trabalho de zeladoria e campanhas de conscientiza\u00e7\u00e3o em unidades de sa\u00fade. A Prefeitura de Ribeir\u00e3o Pires ainda realiza at\u00e9 amanh\u00e3 panfletagens em suas ruas sobre o tema.<\/p>\n<p><strong>Coronav\u00edrus<\/strong><\/p>\n<p>Especialistas dizem que a mobiliza\u00e7\u00e3o de recursos para combater a Covid-19 tem afetado outras campanhas da \u00e1rea da sa\u00fade . \u201cAfetou n\u00e3o s\u00f3 no caso da vigil\u00e2ncia, mas na falta de manuten\u00e7\u00e3o de rotinas importantes\u201d, avalia Carlos Pe\u00e7anha, mestre em sa\u00fade p\u00fablica e diretor t\u00e9cnico da Rentokil, empresa especializada em controle de pragas.<\/p>\n<p>Am\u00e9lia dos Santos, bi\u00f3loga e membro da C\u00e2mara T\u00e9cnica de Res\u00edduos S\u00f3lidos da ABES-SP (Associa\u00e7\u00e3o Brasileira de Engenharia Sanit\u00e1ria e Ambiental), lembra que \u00e9 importante que a popula\u00e7\u00e3o fa\u00e7a a ades\u00e3o \u00e0s campanhas de conscientiza\u00e7\u00e3o. \u201cAs pessoas devem cuidar tanto dos quintais quanto dentro de casa, extinguindo qualquer poss\u00edvel foco (do mosquito)\u201d, lembra.<\/p>\n<p>Daniela Queiroz, epidemiologista e coordenadora da empresa de biotecnologia Forrest, lembra que a pandemia tamb\u00e9m trouxe dificuldades para o trabalho de fiscaliza\u00e7\u00e3o em resid\u00eancias. O Minist\u00e9rio da Sa\u00fade, por meio de nota informativa, recomendou que as visitas n\u00e3o fossem feitas no caso de moradores com mais de 60 anos. \u201cEssa pausa nas visitas representou um deficit nos dados sobre o controle vetorial, bem como os n\u00edveis de infesta\u00e7\u00e3o do Aedes Aegypti\u201d, opina.<\/p>\n<p><a href=\"https:\/\/www.dgabc.com.br\/Noticia\/3806781\/rio-grande-da-serra-e-unica-cidade-sem-combate-a-dengue\">https:\/\/www.dgabc.com.br\/Noticia\/3806781\/rio-grande-da-serra-e-unica-cidade-sem-combate-a-dengue<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Setecidades setecidades@dgabc.com.br | 4435-8319 Rio Grande da Serra \u00e9 \u00fanica cidade sem combate \u00e0 dengue\u00a0 Prefeitura alega que Covid levou \u00e0 reestrutura\u00e7\u00e3o na Sa\u00fade; Santo<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":9565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,236],"tags":[],"class_list":["post-9563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-forrest"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/9565"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=9563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=9563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}