{"id":9235,"date":"2021-10-09T20:21:57","date_gmt":"2021-10-09T23:21:57","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=9235"},"modified":"2021-10-11T20:31:46","modified_gmt":"2021-10-11T23:31:46","slug":"judicializacao-da-saude-e-fator-de-preocupacao","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/judicializacao-da-saude-e-fator-de-preocupacao\/","title":{"rendered":"\u00a0Judicializa\u00e7\u00e3o da Sa\u00fade \u00e9 fator de Preocupa\u00e7\u00e3o"},"content":{"rendered":"<h3><strong>Judicializa\u00e7\u00e3o da Sa\u00fade \u00e9 fator de Preocupa\u00e7\u00e3o<\/strong><\/h3>\n<p>Folha de Londrina<\/p>\n<p>9 e 10 de outubro de 2021<\/p>\n<h3>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9237\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page4_page-0001-1-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page4_page-0001-1-197x300.jpg 197w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page4_page-0001-1-96x146.jpg 96w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page4_page-0001-1-33x50.jpg 33w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page4_page-0001-1-49x75.jpg 49w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page4_page-0001-1.jpg 673w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9236\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page5_page-0001-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page5_page-0001-197x300.jpg 197w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page5_page-0001-96x146.jpg 96w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page5_page-0001-33x50.jpg 33w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page5_page-0001-49x75.jpg 49w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2021\/10\/Folha_de_Londrina2021-10-09_page5_page-0001.jpg 673w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Judicializa\u00e7\u00e3o da Sa\u00fade \u00e9 fator de Preocupa\u00e7\u00e3o Folha de Londrina 9 e 10 de outubro de 2021 \u00a0<\/p>\n","protected":false},"author":111,"featured_media":9071,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,231],"tags":[],"class_list":["post-9235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-nilza-sacoman-advocacia-clientes"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=9235"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/9235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/9071"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=9235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=9235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=9235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}