{"id":8967,"date":"2021-08-27T14:43:58","date_gmt":"2021-08-27T17:43:58","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=8967"},"modified":"2021-08-29T14:45:38","modified_gmt":"2021-08-29T17:45:38","slug":"honpar-realiza-cerimonia-para-o-fechamento-simbolico-do-pronto-socorro-covid-19","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/honpar-realiza-cerimonia-para-o-fechamento-simbolico-do-pronto-socorro-covid-19\/","title":{"rendered":"Honpar realiza cerim\u00f4nia para o fechamento simb\u00f3lico do Pronto Socorro Covid-19"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h4>Honpar realiza cerim\u00f4nia para o fechamento simb\u00f3lico do Pronto Socorro Covid-19<\/h4>\n<div class=\"bottom-title\">\n<div class=\"assinatura\">\n<p class=\"published-by\">Reda\u00e7\u00e3o Tarob\u00e1 News<\/p>\n<p><time datetime=\"2021-08-27T00:37:20Z\">Dia 27 de agosto de 2021<\/time><\/div>\n<div class=\"midias\"><\/div>\n<\/div>\n<div class=\"text\">\n<div class=\"image-author\"><picture><img decoding=\"async\" class=\"image-full\" src=\"https:\/\/tarobanews.2src.link\/assets\/uploads\/noticias\/md-10790239-ed0a-4f45-a013-1b8fe25841c3.jpg\" alt=\"\" \/><\/picture>\n<p class=\"legenda\">Imagem: Divulga\u00e7\u00e3o Honpar<\/p>\n<\/div>\n<div>\n<p>O Hospital Norte Paranaense de Arapongas (Honpar) realizou uma cerim\u00f4nia para o fechamento simb\u00f3lico do Pronto Socorro Covid-19 e fez uma homenagem a todos os funcion\u00e1rios e corpo m\u00e9dico. \u00a0Com a redu\u00e7\u00e3o no n\u00famero de casos o hospital passa a receber apenas pacientes j\u00e1 com o diagn\u00f3stico de interna\u00e7\u00e3o.<\/p>\n<p>Durante 17 meses o HONPAR internou 3114 casos suspeitos, sendo destes 2422 com exame positivo. Apesar das perdas, 60% destes paciente venceram a doen\u00e7a.<\/p>\n<p>Na homenagem os profissionais do Eixo COVID receberam um caf\u00e9 especial e um certificado de reconhecimento por toda dedica\u00e7\u00e3o aos pacientes neste momento cr\u00edtico. Tamb\u00e9m foi realizado um almo\u00e7o e um jantar especial.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Honpar realiza cerim\u00f4nia para o fechamento simb\u00f3lico do Pronto Socorro Covid-19 Reda\u00e7\u00e3o Tarob\u00e1 News Dia 27 de agosto de 2021 Imagem: Divulga\u00e7\u00e3o Honpar O Hospital<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":5251,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,230],"tags":[],"class_list":["post-8967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-honpar-hospital-norte-paranaense"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/8967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=8967"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/8967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/5251"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=8967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=8967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=8967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}