{"id":8185,"date":"2021-04-12T11:46:14","date_gmt":"2021-04-12T14:46:14","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=8185"},"modified":"2021-04-30T11:47:54","modified_gmt":"2021-04-30T14:47:54","slug":"obras-de-novo-bairro-de-londrina-comecam-ainda-neste-mes","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/obras-de-novo-bairro-de-londrina-comecam-ainda-neste-mes\/","title":{"rendered":"Obras de novo bairro de Londrina come\u00e7am ainda neste m\u00eas"},"content":{"rendered":"<div class=\"conteudo\">\n<p>A assinatura do primeiro contrato de financiamento com a Caixa de um total de 866 moradias do bairro planejado Bem Viver Londrina foi oficializada na tarde desta segunda-feira no gabinete do prefeito Marcelo Belinati. E a agente de sa\u00fade do munic\u00edpio Juliana Vincoleto, 36 anos, representou as quase 280 fam\u00edlias desta 1\u00aa etapa do projeto que j\u00e1 tiveram a documenta\u00e7\u00e3o aprovada e v\u00e3o assinar a papelada nos pr\u00f3ximos dias.<\/p>\n<p>\u200b\u200bCom a assinatura do primeiro contrato de financiamento as obras do novo bairro ser\u00e3o iniciadas pela construtora Pacaembu, que esta semana come\u00e7a a limpeza da \u00e1rea e a montagem do canteiro de obras no Cinco Conjuntos.<\/p>\n<p>\u200bCom investimento de R$ 115 milh\u00f5es, o empreendimento \u00e9 destinado a fam\u00edlias com renda mensal a partir de R$ 1.600,00 e integra o programa Casa F\u00e1cil Paran\u00e1 da Companhia de Habita\u00e7\u00e3o do Paran\u00e1, a Cohapar, em parceria com a Companhia de Habita\u00e7\u00e3o de Londrina. As moradias podem ser financiadas exclusivamente com a Caixa e as parcelas giram em torno de R$ 360.<\/p>\n<p>Durante a solenidade de assinatura do contrato, o prefeito Marcelo Belinati destacou os 2.500 empregos que devem ser gerados com o empreendimento, que no total ter\u00e1 mais de 850 unidades divididas em tr\u00eas m\u00f3dulos.<\/p>\n<p>O Bem Viver Londrina ser\u00e1 um bairro planejado, com casas n\u00e3o geminadas de 46 metros quadrados, divididas em sala integrada, dois quartos, cozinha integrada e um banheiro, e com possibilidade de amplia\u00e7\u00e3o. Os terrenos possuem 160 metros e toda a infraestrutura, como supermercados, unidades de sa\u00fade e escolas pr\u00f3ximas.<\/p>\n<p>\u200bO valor de cada unidade come\u00e7a em R$ 128 mil para fam\u00edlias com renda mensal a partir de R$ 1.600,00 e os interessados podem receber um subs\u00eddio de at\u00e9 R$ 36 mil por meio do programa habitacional Casa Verde e Amarela. O valor de entrada pode ser parcelado em at\u00e9 60 vezes direto com a construtora e o saldo pode ser financiado em at\u00e9 360 meses, com a possibilidade de uso do FGTS.<\/p>\n<p>\u200b\u200bPara as fam\u00edlias interessadas, a Loja Pacaembu Construtora fica na Avenida Saul Elkind, 1.470, Conjunto Vivi Xavier. O funcionamento \u00e9 de segunda a sexta-feira, das 9h \u00e0s 17h. O telefone para informa\u00e7\u00f5es \u00e9 o 3771 0359. \u200bA construtora tamb\u00e9m est\u00e1 atendendo e recebendo a documenta\u00e7\u00e3o online pelo WhatsApp (42) 99143 7191.<\/p>\n<\/div>\n<div class=\"item-por\"><a href=\"https:\/\/cbnlondrina.com.br\/materias\/obras-de-novo-bairro-de-londrina-comecam-ainda-este-mes\">Por\u00a0<b>Marcos Garrido<\/b><\/a><\/div>\n<div class=\"lista-audios\">\n<div class=\"lista-audio\">\n<h3><\/h3>\n<div class=\"bloco-player\">\n<div class=\"audio-player\">\n<div id=\"mep_0\" class=\"mejs-container svg mejs-audio\" tabindex=\"0\" role=\"application\" aria-label=\"Audio Player\">\n<div class=\"mejs-inner\">\n<div class=\"mejs-mediaelement\"><\/div>\n<div class=\"mejs-layers\"><\/div>\n<div class=\"mejs-controls\">\n<div class=\"mejs-button mejs-playpause-button mejs-play\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A assinatura do primeiro contrato de financiamento com a Caixa de um total de 866 moradias do bairro planejado Bem Viver Londrina foi oficializada na tarde<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":4319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[233],"tags":[],"class_list":["post-8185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pacaembu-construtora"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/8185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=8185"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/8185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=8185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=8185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=8185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}