{"id":7558,"date":"2020-07-14T15:33:41","date_gmt":"2020-07-14T18:33:41","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=7558"},"modified":"2020-07-15T15:35:09","modified_gmt":"2020-07-15T18:35:09","slug":"governo-federal-amplia-prazo-para-suspensao-de-contratos-de-trabalho-e-reducao-de-jornada","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/governo-federal-amplia-prazo-para-suspensao-de-contratos-de-trabalho-e-reducao-de-jornada\/","title":{"rendered":"Governo Federal amplia prazo para suspens\u00e3o de contratos de trabalho e redu\u00e7\u00e3o de jornada"},"content":{"rendered":"<div class=\"conteudo\">\n<p>O Governo Federal ampliou por meio de decreto o prazo do programa que permite a redu\u00e7\u00e3o de jornada e de sal\u00e1rio, al\u00e9m da suspens\u00e3o de contratos de trabalho. A redu\u00e7\u00e3o em at\u00e9 70% de trabalho e de sal\u00e1rios passa de 3 para 4 meses, e a suspens\u00e3o dos contratos foi ampliada de 2 para 4 meses.<\/p>\n<p>A MP que foi transformada em lei, foi sancionada inicialmente no dia 6 de junho. Com o decreto desta ter\u00e7a-feira, a amplia\u00e7\u00e3o pode chegar a 120 dias.<\/p>\n<p>De acordo com a advogada Fernanda Viotto, a medida amplia todos os seguimentos.<\/p>\n<p>Fernanda ressalta quatro fatores importantes que asseguram o trabalhador na manuten\u00e7\u00e3o do emprego. Entre eles est\u00e1 que a suspens\u00e3o do contrato de trabalho poder\u00e1 ser efetuada de forma fracionada, em per\u00edodos sucessivos ou intercalados, desde que esses per\u00edodos sejam iguais ou superiores a 10 dias e que n\u00e3o seja excedido o prazo de 120 dias. Isso \u00e9 v\u00e1lido para suspens\u00e3o tempor\u00e1ria em meio a quarentenas estabelecidas de forma regional. O programa que quer a manuten\u00e7\u00e3o do emprego, prev\u00ea ainda que ao t\u00e9rmino desse per\u00edodo o empregado n\u00e3o pode se mandado embora, pelo menos por igual per\u00edodo.<\/p>\n<p>Dados divulgados pelo Minist\u00e9rio da Economia, registram que mais de 12 milh\u00f5es de contratos j\u00e1 foram assinados desde a implanta\u00e7\u00e3o do benef\u00edcio emergencial para preserva\u00e7\u00e3o do emprego em meio a pandemia do novo Coronav\u00edrus.<\/p>\n<\/div>\n<div class=\"item-por\"><a href=\"https:\/\/cbnlondrina.com.br\/materias\/governo-federal-amplia-prazo-para-suspensao-de-contratos-de-trabalho-e-reducao-de-jornada\">Por\u00a0<b>Bruno Carraro<\/b><\/a><\/div>\n<div class=\"lista-audios\">\n<div class=\"lista-audio\">\n<h3><\/h3>\n<div class=\"bloco-player\">\n<div class=\"audio-player\">\n<div id=\"mep_0\" class=\"mejs-container svg mejs-audio\" tabindex=\"0\" role=\"application\" aria-label=\"Audio Player\">\n<div class=\"mejs-inner\">\n<div class=\"mejs-mediaelement\"><\/div>\n<div class=\"mejs-layers\"><\/div>\n<div class=\"mejs-controls\">\n<div class=\"mejs-button mejs-playpause-button mejs-play\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Governo Federal ampliou por meio de decreto o prazo do programa que permite a redu\u00e7\u00e3o de jornada e de sal\u00e1rio, al\u00e9m da suspens\u00e3o de contratos<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":4319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[229],"tags":[],"class_list":["post-7558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viotto-pereira-advogados-associados"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/7558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=7558"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/7558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=7558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=7558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=7558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}