{"id":7545,"date":"2020-07-07T18:03:21","date_gmt":"2020-07-07T21:03:21","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=7545"},"modified":"2020-07-09T18:04:36","modified_gmt":"2020-07-09T21:04:36","slug":"decreto-estadual-deve-ser-cumprido-pelos-comerciantes-segundo-a-lei","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/decreto-estadual-deve-ser-cumprido-pelos-comerciantes-segundo-a-lei\/","title":{"rendered":"Decreto estadual deve ser cumprido pelos comerciantes segundo a lei"},"content":{"rendered":"<div class=\"conteudo\">\n<p>O rep\u00f3rter Bruno Carraro conversou com o advogado Pedro Vasconcellos, e tem mais detalhes. Vamos acompanhar a entrevista.<\/p>\n<\/div>\n<div class=\"item-por\"><a href=\"https:\/\/cbnlondrina.com.br\/materias\/decreto-estadual-deve-ser-cumprido-pelos-comerciantes-segundo-a-lei\">Por\u00a0<b>Bruno Carraro<\/b><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O rep\u00f3rter Bruno Carraro conversou com o advogado Pedro Vasconcellos, e tem mais detalhes. Vamos acompanhar a entrevista. Por\u00a0Bruno Carraro<\/p>\n","protected":false},"author":111,"featured_media":4319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[160],"tags":[],"class_list":["post-7545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vilela-berbel-e-mitne"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/7545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=7545"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/7545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=7545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=7545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=7545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}