{"id":7211,"date":"2020-04-27T11:18:34","date_gmt":"2020-04-27T14:18:34","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=7211"},"modified":"2020-05-15T11:26:35","modified_gmt":"2020-05-15T14:26:35","slug":"recebimento-indevido-do-auxilio-emergencial-pode-dar-ate-cinco-anos-de-prisao","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/recebimento-indevido-do-auxilio-emergencial-pode-dar-ate-cinco-anos-de-prisao\/","title":{"rendered":"Recebimento indevido do Aux\u00edlio Emergencial pode dar at\u00e9 cinco anos de pris\u00e3o"},"content":{"rendered":"<p>Quem recebe indevidamente pode ser enquadrado nos crimes de falsidade ideol\u00f3gica e estelionato<\/p>\n<p>O governo federal implantou o aux\u00edlio emergencial para tentar reduzir os impactos financeiros causados pelo novo coronav\u00edrus na economia. O benef\u00edcio est\u00e1 sendo destinado para os trabalhadores informais, microempreendedores individuais, aut\u00f4nomos e desempregados, que n\u00e3o recebem seguro-desemprego ou outro aux\u00edlio governamental. Quem tiver aprovada a solicita\u00e7\u00e3o receber\u00e1 R$ 600 por um per\u00edodo de tr\u00eas meses, podendo ser prorrogado conforme decis\u00e3o do governo.<br \/>\nMas muitas pessoas que n\u00e3o se enquadram nesses requisitos t\u00eam feito a solicita\u00e7\u00e3o do auxilio, omitido informa\u00e7\u00f5es com o objetivo de receber indevidamente o benef\u00edcio. O advogado Lucas Pretto, destaca que isso pode ser caracterizado como crime de falsidade ideol\u00f3gica, o que pode gerar uma deten\u00e7\u00e3o de at\u00e9 cinco anos.<br \/>\n\u201cO cidad\u00e3o que solicitar o benef\u00edcio declarando ou omitindo dolosamente circunst\u00e2ncia que sabe que excluiria o direito ao benef\u00edcio, pode estar cometendo os crimes de falsidade ideol\u00f3gica e estelionato, consumado ou tentado a depender se houver ou n\u00e3o o recebimento do benef\u00edcio, com a agravante de ser cometido contra a assist\u00eancia social, o que aumenta em um ter\u00e7o a pena do estelionato que varia de um a cinco anos de pris\u00e3o\u201d, comentou.<br \/>\nA libera\u00e7\u00e3o dos saques das poupan\u00e7as digitais come\u00e7a na pr\u00f3xima segunda-feira 27 de abril, para aqueles que nasceram nos meses de janeiro e fevereiro, no dia 28 para os nascidos em mar\u00e7o e abril, 29 para os nascidos em maio e junho, 30 para os nascidos em julho e agosto. Em maio, ser\u00e1 a vez de os nascidos em setembro e outubro sacarem o benef\u00edcio no dia 4; e os nascidos em novembro e dezembro, no dia 5.<\/p>\n<p><a href=\"https:\/\/ednoticias.com\/recebimento-indevido-do-auxilio-emergencial-pode-dar-ate-cinco-anos-de-prisao\/\">Rodolfo Salloum<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem recebe indevidamente pode ser enquadrado nos crimes de falsidade ideol\u00f3gica e estelionato O governo federal implantou o aux\u00edlio emergencial para tentar reduzir os impactos financeiros<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":110,"featured_media":7212,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,229],"tags":[],"class_list":["post-7211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-viotto-pereira-advogados-associados"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/7211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=7211"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/7211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/7212"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=7211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=7211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=7211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}