{"id":6912,"date":"2019-11-11T05:15:11","date_gmt":"2019-11-11T08:15:11","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=6912"},"modified":"2019-11-13T05:18:52","modified_gmt":"2019-11-13T08:18:52","slug":"colegio-maxi-e-a-unica-escola-do-parana-a-ter-selo-de-escola-referencia-do-google-for-education","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/colegio-maxi-e-a-unica-escola-do-parana-a-ter-selo-de-escola-referencia-do-google-for-education\/","title":{"rendered":"Col\u00e9gio Maxi \u00e9 a \u00fanica escola do Paran\u00e1 a ter selo de escola refer\u00eancia do Google For Education"},"content":{"rendered":"<p>Desde a implanta\u00e7\u00e3o do Google for Education, em 2015, o\u00a0<a href=\"https:\/\/www.colegiomaxi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Col\u00e9gio Maxi\u00a0<\/a>vem investindo na forma\u00e7\u00e3o dos educadores, nos ambientes diferenciados \u2013 como a cria\u00e7\u00e3o de tr\u00eas Salas Google \u2013 e na orienta\u00e7\u00e3o aos alunos e professores para o uso cont\u00ednuo e efetivo dessa plataforma. A satisfa\u00e7\u00e3o diante da nova tecnologia, aliada aos resultados concretos na aprendizagem dos alunos, fez que o programa tivesse plena ades\u00e3o, tornando o Maxi a primeira escola do Paran\u00e1 e uma das quatro do sul do Brasil a receber do Google o Selo de Escola de Refer\u00eancia Google for Education.<\/p>\n<div class=\"imagefmt\">\n<div class=\"e8 center\">Divulga\u00e7\u00e3o<\/div>\n<p><img decoding=\"async\" class=\"imgz\" title=\"Divulga\u00e7\u00e3o - Alunos na sala Google\" src=\"https:\/\/www.bonde.com.br\/img\/bondenews\/2019\/11\/img_1_69_2161.jpg\" alt=\"Divulga\u00e7\u00e3o - Alunos na sala Google\" \/><\/p>\n<div class=\"seedtag-gohan seedtag-adunit st-in-image\">\n<div class=\"st-container\">\n<div class=\"st-adunit-component st-adunit-component_ad-view\">\n<div class=\"st-container\">\n<div class=\"st-ad-wrapper\">Alunos na sala Google<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"sc_intxt_container\">\n<div>\n<div id=\"smartIntxt\" class=\"fixed_intext_init\" data-id=\"_mwayss-a790b19fa695c1b6aff666405687c603\" data-smartplay-instance-id=\"0\"><\/div>\n<div id=\"sc_ava_companion\" class=\"sc_intxt_hided\">Jana\u00edna Tais Gardenal Fenato, coordenadora de Tecnologia em Educa\u00e7\u00e3o do <a href=\"https:\/\/www.colegiomaxi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Col\u00e9gio Maxi\u00a0<\/a>e Google Educator Trainer, explica a import\u00e2ncia desse reconhecimento: &#8220;O Selo significa que a empresa Google confirma todos os esfor\u00e7os do Col\u00e9gio Maxi em implementar solu\u00e7\u00f5es inovadoras e que a escola utiliza as ferramentas educacionais Google de modo colaborativo para motivar e melhorar a forma como os professores ensinam e os alunos aprendem\u201d.<\/div>\n<\/div>\n<\/div>\n<p>Para a obten\u00e7\u00e3o do Selo, o Google estabelece uma s\u00e9rie de crit\u00e9rios:<\/p>\n<p>\u2022 Utiliza\u00e7\u00e3o das ferramentas Google for Education e Chromebooks, realizando projetos inovadores e impactantes para professores e alunos.<br \/>\n\u2022 Ter no m\u00ednimo 100 Chromebooks com CMC (licen\u00e7as) Google.<br \/>\n\u2022 Contas GSuite for Education para 100% da \u00e1rea pedag\u00f3gica; 100% dos alunos a partir do 6\u00ba ano do Ensino Fundamental 2; 30% dos alunos usando o GSuite for Education em sala de aula de forma colaborativa com o professor, ao menos uma vez a cada 30 dias; e 30% dos alunos usando o Google Classroom.<br \/>\n\u2022 Certifica\u00e7\u00f5es internacionais exigidas: um professor Google Educator Trainer para dar continuidade nos treinamentos e coordenar a transforma\u00e7\u00e3o digital na escola; 20% da \u00e1rea pedag\u00f3gica da escola com certificado Google Educator N\u00edvel 1; 5% da \u00e1rea pedag\u00f3gica da escola com o certificado Google Educator N\u00edvel 2.<\/p>\n<p>Sobre os benef\u00edcios do Google for Education, a coordenadora de TE comenta: &#8220;Os ganhos s\u00e3o gigantescos. A equipe pedag\u00f3gica e os professores personalizaram o aprendizado, garantindo melhor desempenho de suas turmas\u201d, avalia Jana\u00edna.<\/p>\n<p><b>ENVOLVIMENTO DOS PROFESSORES<\/b><\/p>\n<div class=\"imagefmt\">\n<div class=\"e8 center\">Divulga\u00e7\u00e3o<\/div>\n<p><img decoding=\"async\" class=\"imgz\" style=\"border: 0px; max-width: 100%;\" title=\"Divulga\u00e7\u00e3o - Sala Google na Unidade Avenida &lt;a href='\/tags\/maringa\/' target='_blank'&gt;Maring\u00e1&lt;\/a&gt;\" src=\"https:\/\/www.bonde.com.br\/img\/bondenews\/2019\/11\/img_1_69_2164.jpg\" alt=\"Divulga\u00e7\u00e3o - Sala Google na Unidade Avenida &lt;a href='\/tags\/maringa\/' target='_blank'&gt;Maring\u00e1&lt;\/a&gt;\" \/><br \/>\n<span class=\"f12 mgt-5\">Sala Google na Unidade Avenida\u00a0<a href=\"https:\/\/www.bonde.com.br\/tags\/maringa\/\" target=\"_blank\" rel=\"noopener noreferrer\">Maring\u00e1<\/a><\/span><\/p>\n<\/div>\n<p>Fernando Francisco Pereira, professor de Matem\u00e1tica do Fundamental 2 do Col\u00e9gio Maxi, explica a versatilidade do programa: &#8220;Desde que o Google for Education foi implantado, percebi que era um ambiente virtual de seguran\u00e7a e autonomia dos alunos. Tive uma identifica\u00e7\u00e3o t\u00e3o grande que fui aprendendo e querendo desenvolver novos projetos. Tanto que resolvi participar no ano passado do Concurso Boas Pr\u00e1ticas, com ideias inovadoras para a educa\u00e7\u00e3o. E este ano me inscrevi tamb\u00e9m\u201d.<\/p>\n<p>O professor do Maxi cita outros benef\u00edcios: &#8220;Uma quest\u00e3o bem interessante \u00e9 a ades\u00e3o \u00e0s tarefas de casa. Depois que o Google for Education foi implantado, os alunos passaram a fazer mais tarefas. O indicativo NFT \u2013 N\u00e3o Fez Tarefa \u2013 \u00e9 m\u00ednimo. Isso comprova a efic\u00e1cia do programa no incentivo ao estudo, pois trabalha com a linguagem do aluno de hoje\u201d.<\/p>\n<p><b>AULAS COM \u00d3CULOS VR<\/b><\/p>\n<p>Sobre as tecnologias adotadas pelo Col\u00e9gio, Pereira comenta: &#8220;As Salas Google potencializam o uso da plataforma, pois \u00e9 um ambiente descontra\u00eddo, high tech e fora dos padr\u00f5es da sala de aula, com um Chromebook por aluno, um notebook concebido pelo Google com sistema operacional Chrome OS\u201d e com sistema exclusivo de gerenciamento de seguran\u00e7a por meio do Admin Google.<\/p>\n<div class=\"imagefmt\">\n<div class=\"e8 center\">Divulga\u00e7\u00e3o<\/div>\n<p><img decoding=\"async\" class=\"imgz\" title=\"Divulga\u00e7\u00e3o\" src=\"https:\/\/www.bonde.com.br\/img\/bondenews\/2019\/11\/img_1_69_2163.jpg\" alt=\"Divulga\u00e7\u00e3o\" \/><\/p>\n<\/div>\n<p>Outra ferramenta que os alunos gostam muito s\u00e3o os \u00f3culos de realidade virtual disponibilizados nas Salas Google. A realidade virtual \u00e9 uma tecnologia de interface que atua nos sentidos do usu\u00e1rio, por meio de um ambiente simulado, criado a partir de um sistema computacional. Ao induzir efeitos visuais, sonoros e at\u00e9 t\u00e1teis, propicia a imers\u00e3o completa em um cen\u00e1rio ou local, com ou sem intera\u00e7\u00e3o do usu\u00e1rio: &#8220;A realidade virtual \u00e9 algo fant\u00e1stico, pois permite que nossos alunos se sintam em diferentes lugares do mundo, em quaisquer per\u00edodos da hist\u00f3ria. Um aluno pode, por exemplo, ser um homem da caverna e interagir com personagens daquela \u00e9poca. \u00c9 uma ferramenta disponibilizada pelo Maxi que eles adoram\u201d, comenta o professor de Matem\u00e1tica.<\/p>\n<p><b>GOOGLE FOR EDUCATION CAPACITA\u00c7\u00c3O CONT\u00cdNUA DOS EDUCADORES<\/b><\/p>\n<p>Veja a seguir as explica\u00e7\u00f5es de Jana\u00edna Fenato, Google Educator Trainer, respons\u00e1vel por orientar os educadores na utiliza\u00e7\u00e3o do Google for Education.<\/p>\n<p><b>FORMA\u00c7\u00c3O DOS EDUCADORES\u00a0<a href=\"https:\/\/www.colegiomaxi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MAXI<\/a><\/b><\/p>\n<p>O princ\u00edpio b\u00e1sico do Google for Education \u00e9 &#8220;Educadores dedicados aprendem por toda a vida\u201d, por isso \u00e9 importante inovar na experi\u00eancia de ensinar e aprender. Os professores usam os in\u00fameros recursos dispon\u00edveis na Internet a favor da educa\u00e7\u00e3o e, principalmente, participam dos cursos de forma\u00e7\u00e3o e treinamento para conquistar as certifica\u00e7\u00f5es Google for Education.<\/p>\n<div class=\"imagefmt\">\n<div class=\"e8 center\">Divulga\u00e7\u00e3o<\/div>\n<p><img decoding=\"async\" class=\"imgz\" title=\"Divulga\u00e7\u00e3o - Sala Google I - Unidade Duque de Caxias\" src=\"https:\/\/www.bonde.com.br\/img\/bondenews\/2019\/11\/img_1_69_2162.jpg\" alt=\"Divulga\u00e7\u00e3o - Sala Google I - Unidade Duque de Caxias\" \/><br \/>\n<span class=\"f12 mgt-5\">Sala Google I &#8211; Unidade Duque de Caxias<\/span><\/p>\n<\/div>\n<p><b>FERRAMENTAS F\u00c1CEIS E INTUITIVAS<\/b><\/p>\n<p>As ferramentas de produtividade Google for Education s\u00e3o intuitivas e acess\u00edveis. Isso ajuda os professores a gerenciar de maneira simples suas atividades. Hoje, ap\u00f3s tr\u00eas anos do Google for Education, os professores n\u00e3o se limitam a uma ou duas ferramentas, mas usam v\u00e1rias experi\u00eancias de aprendizagem, de acordo com as habilidades, o ritmo e o desenvolvimento de cada aluno. Os professores utilizam a &#8220;gamifica\u00e7\u00e3o\u201d em revis\u00f5es de prova para melhorar o desempenho dos alunos e dar um feedback construtivo. O Google classifica a &#8220;gamifica\u00e7\u00e3o\u201d como uma estrat\u00e9gia de aprendizagem ativa.<\/p>\n<p>Divulga\u00e7\u00e3o<\/p>\n<div class=\"imagefmt\"><img decoding=\"async\" class=\"imgz\" title=\"Divulga\u00e7\u00e3o - Sala Google II - Unidade Avenida Duque de Caixas\" src=\"https:\/\/www.bonde.com.br\/img\/bondenews\/2019\/11\/img_1_69_2165.jpg\" alt=\"Divulga\u00e7\u00e3o - Sala Google II - Unidade Avenida Duque de Caixas\" \/><br \/>\n<span class=\"f12 mgt-5\">Sala Google II &#8211; Unidade Avenida Duque de Caixas<\/span><\/div>\n<p><b>&#8220;Essa plataforma fala a nossa linguagem!\u201d<\/b><br \/>\nConfira o depoimento de alguns alunos sobre a utiliza\u00e7\u00e3o das ferramentas do Google for Education.<\/p>\n<p>&#8220;Entrei no Maxi no 6\u00ba ano do Ensino Fundamental e acompanhei toda a implanta\u00e7\u00e3o do programa Google for Education. \u00c9 um m\u00e9todo inovador, uma forma de aprender diferenciada e mais objetiva do que a aula tradicional que favorece muito o contato com o professor. D\u00e1 para fazer tarefa mais facilmente, tirar d\u00favidas e ter acesso a atividades e desafios extras. Trata-se de uma linguagem acess\u00edvel, com a qual minha gera\u00e7\u00e3o est\u00e1 acostumada. At\u00e9 quem n\u00e3o domina muito tecnologia aprende sem problemas. Desenvolvemos v\u00e1rios conte\u00fados e trabalhamos de uma forma muito mais produtiva. Sem falar que ajuda na intera\u00e7\u00e3o com os colegas, pois fazemos muitos trabalhos em grupo. Outro detalhe \u00e9 a Sala Google. Gosto muito desse ambiente.\u201d<br \/>\n<b>Henrique Santos Nakadomari \u2013 1\u00aa s\u00e9rie do Ensino M\u00e9dio<\/b><\/p>\n<p>&#8220;O Google for Education nos proporciona uma aula diferenciada, mais pr\u00e1tica e com muitas imagens. \u00c9 uma ferramenta que acompanha o mundo moderno. Fazemos as tarefas de forma mais f\u00e1cil, pois h\u00e1 muitas ferramentas \u00e0 disposi\u00e7\u00e3o, busca facilitada e um ambiente de navega\u00e7\u00e3o seguro. Os professores ajudam e trabalhamos com pesquisas e apresenta\u00e7\u00f5es. Adoro as aulas da Sala Google, pois \u00e9 um espa\u00e7o bacana, extrovertido e din\u00e2mico. \u00c9 um diferencial do Maxi esse programa.\u201d<br \/>\n<b>Ana Luisa Gomes Leme da Silva \u2013 8\u00ba ano do Ensino Fundamental<\/b><\/p>\n<p><a href=\"https:\/\/www.bonde.com.br\/educacao\/noticias\/colegio-maxi-unica-escola-do-parana-a-ter-o-selo-de-escola-de-referencia-do-google-for-education-507564.html\"><i>Este conte\u00fado \u00e9 de autoria do Col\u00e9gio Maxi.<\/i><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde a implanta\u00e7\u00e3o do Google for Education, em 2015, o\u00a0Col\u00e9gio Maxi\u00a0vem investindo na forma\u00e7\u00e3o dos educadores, nos ambientes diferenciados \u2013 como a cria\u00e7\u00e3o de tr\u00eas Salas<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":110,"featured_media":4451,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,203],"tags":[],"class_list":["post-6912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-colegio-maxi-londrina"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=6912"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4451"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=6912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=6912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=6912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}