{"id":6852,"date":"2019-10-10T23:10:13","date_gmt":"2019-10-11T02:10:13","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=6852"},"modified":"2019-10-10T23:11:44","modified_gmt":"2019-10-11T02:11:44","slug":"nova-geracao-do-hb20-e-apresentada-em-maringa","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/nova-geracao-do-hb20-e-apresentada-em-maringa\/","title":{"rendered":"Nova gera\u00e7\u00e3o do HB20 \u00e9 apresentada em Maring\u00e1"},"content":{"rendered":"<div class=\"pub_12 bg-branco col-xs-12 no-padding\">\n<div class=\"close-pub-12\"><\/div>\n<\/div>\n<section class=\"interna  col-xs-12 no-padding\">\n<div class=\"col-xs-12 col-sm-9 no-padding-left noticia-body\">\n<div class=\"col-xs-12 no-padding\">\n<div class=\"cabecalho col-xs-10 no-padding\">\n<div class=\"conteudo-patrocinado-flag ff-montserrat texto-upper\"><\/div>\n<\/div>\n<div class=\"col-xs-2 no-padding\"><\/div>\n<\/div>\n<div class=\"texto col-xs-12 no-padding\">\n<div class=\"post-conteudo-video col-xs-12 no-padding\"><iframe loading=\"lazy\" class=\"video video-youtube\" src=\"https:\/\/www.youtube.com\/embed\/WJTshdIhz8c\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div class=\"post-conteudo-texto col-xs-12 no-padding\">\n<article class=\"ff-opensans fc-cinza\">O novo Hb-20, as v\u00e9speras do lan\u00e7amento das vendas no Brasil \u2013 com in\u00edcio esta semana, ter\u00e1 sua apresenta\u00e7\u00e3o antecipada nesta sexta-feira na Hyundai Lovat em Maring\u00e1. O Test Drive j\u00e1 pode ser feito e o lema \u00e9 \u201cA ousadia vai invadir as ruas\u201d.<\/p>\n<p>A Hyundai lan\u00e7a desta vez a nova gera\u00e7\u00e3o do modelo que foi um dos respons\u00e1veis por revolucionar o segmento de entrada h\u00e1 exatos sete anos, onde vendeu mais de um milh\u00e3o de unidades e conquistou o cora\u00e7\u00e3o dos brasileiros.<\/p>\n<p>Com visual atualizado, eles ficaram mais espa\u00e7osos, evolu\u00edram no acabamento e trazem tecnologias in\u00e9ditas na categoria. Outra novidade \u00e9 a chegada de um novo motor 1.0 Turbo com inje\u00e7\u00e3o direta. Os pre\u00e7os ainda n\u00e3o foram divulgados, exceto que a vers\u00e3o de entrada partir\u00e1 de R$ 46.490.<\/p>\n<p>Esta nova gera\u00e7\u00e3o ainda apresenta uma s\u00e9rie de itens como: sistema de frenagem aut\u00f4noma de emerg\u00eancia na vers\u00e3o Diamond Plus, alerta de mudan\u00e7a de faixa, dire\u00e7\u00e3o com assist\u00eancia el\u00e9trica, assistente de partida em rampas, ar condicionado digital, 4 airbags, central multim\u00eddia com tela t\u00e1til de 8 polegadas. Com ainda controle de estabilidade e de tra\u00e7\u00e3o, acendimento autom\u00e1tico de far\u00f3is, piloto autom\u00e1tico e trocas de marcha por aletas atr\u00e1s do volante.<\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/gmconline.com.br\/uploads\/51321d2114607c89118db9c6eefc6339.jpg\" alt=\"Bloco de Imagem\" \/><\/p>\n<\/article>\n<\/div>\n<div class=\"post-conteudo-imagem col-xs-12 no-padding\">\n<div class=\"col-xs-12 bg-cinza2\"><strong>O NOVO ROBUSTO<\/strong><\/div>\n<\/div>\n<div class=\"post-conteudo-texto col-xs-12 no-padding\">\n<article class=\"ff-opensans fc-cinza\">A vers\u00e3o topo de linha oferece maior agilidade no tr\u00e2nsito, ultrapassagens mais seguras e tranquilidade para subir as ladeiras. A for\u00e7a do Motor TGDi flex com inje\u00e7\u00e3o direta entrega 120cv de pot\u00eancia e 17,5 kgfm de torque, a 1750 RPM, na vers\u00e3o a \u00e1lcool, com c\u00e2mbio autom\u00e1tico de 6 marchas.<\/p>\n<p>Com inje\u00e7\u00e3o direta de combust\u00edvel e sistema de pr\u00e9-aquecimento de combust\u00edvel, o novo propulsor ficar\u00e1 restrito \u00e0s vers\u00f5es mais caras do HB20, sendo mantido o modelo atual, onde o motor agora com Duplo comando de v\u00e1lvulas vari\u00e1vel, teve um aumento de pot\u00eancia para 130 CV, trazendo mais conforto e economia.<\/p>\n<p>O modelo tamb\u00e9m est\u00e1 20 mm maior no entre eixos, e 20 mm maior na largura, gra\u00e7as a um enxerto na base, chegando aos 2.530 mm de comprimento e 1.470 mm de altura.<\/p>\n<\/article>\n<\/div>\n<div class=\"post-conteudo-imagem col-xs-12 no-padding\">\n<div class=\"col-xs-12 no-padding img-container\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/gmconline.com.br\/uploads\/e389b38464400290562ecf52e3fc8cd7.jpeg\" alt=\"Bloco de Imagem\" \/><\/div>\n<div class=\"col-xs-12 bg-cinza2\"><strong>Seguran\u00e7a<\/strong><\/div>\n<\/div>\n<div class=\"post-conteudo-texto col-xs-12 no-padding\">\n<article class=\"ff-opensans fc-cinza\">A Hyundai ir\u00e1 vender o HB20 com at\u00e9 04 airbags e freios ABS, os itens que j\u00e1 s\u00e3o obrigat\u00f3rios em todos os carros. Recebe controle de estabilidade e tra\u00e7\u00e3o apenas a partir da vers\u00e3o Evolution, tanto para o hatch quanto para o sed\u00e3. A configura\u00e7\u00e3o Diamond adiciona airbags laterais, enquanto a topo de linha Diamond Plus ganha frenagem autom\u00e1tica de emerg\u00eancia, monitoramento de press\u00e3o nos pneus e alerta de mudan\u00e7a de faixa.<\/p>\n<p><strong>Exclusivo sistema de prote\u00e7\u00e3o e seguran\u00e7a<\/strong><\/p>\n<p>O Sistema de Alerta e Frenagem Aut\u00f4nomo, exclusivo na categoria, utiliza a c\u00e2mera no para-brisa para identificar carros e pedestres a frente, em caso de risco de colis\u00e3o, \u00e9 emitido um alerta sonoro e os freios s\u00e3o acionados.<\/p>\n<\/article>\n<\/div>\n<p><ins class=\"adsbygoogle adsbygoogle-banner-conteudo\" data-ad-client=\"ca-pub-2497380063583452\" data-ad-slot=\"5599132260\" data-full-width-responsive=\"true\"><\/ins><\/p>\n<div class=\"post-conteudo-imagem col-xs-12 no-padding\">\n<div class=\"col-xs-12 no-padding img-container\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/gmconline.com.br\/uploads\/9657461df43212158e12f99c75e1a1df.jpg\" alt=\"Bloco de Imagem\" \/><\/div>\n<div class=\"col-xs-12 bg-cinza2\"><strong>Alerta de Mudan\u00e7a de faixa<\/strong><\/div>\n<\/div>\n<div class=\"post-conteudo-texto col-xs-12 no-padding\">\n<article class=\"ff-opensans fc-cinza\">Por meio de c\u00e2mera localizada no para-brisa, o sistema pode identificar as faixas da frente, e caso o ve\u00edculo saia da sua trajet\u00f3ria, o Sistema alerta o motorista por meio de luzes no painel e alerta sonoro.<\/p>\n<p>Uma enquete feita pelo site UOL mostrou a disputa e preferencia do consumidor. Onix x HB20, os dois carros mais vendidos do Brasil apresentaram suas vers\u00f5es 2020 no m\u00eas de setembro\/outubro. E o Hyundai HB20, com visual mais ousado dividiu opini\u00f5es, mas ganhou a prefer\u00eancia dos leitores de UOL. A enquete chegou a quase 2 milh\u00f5es de votos.<\/p>\n<p>O carro da montadora sul-coreana foi eleito pelo p\u00fablico como o melhor lan\u00e7amento entre os hatches, com 58% dos votos. J\u00e1 o modelo da Chevrolet, atual l\u00edder de vendas, ficou com 42% da prefer\u00eancia. No total, a vota\u00e7\u00e3o contou com 1.912.934 votos.<\/p>\n<p>O restante da fam\u00edlia tamb\u00e9m ser\u00e1 apresentada em breve: o novo HB20S (previs\u00e3o lan\u00e7amento \u202a01\/11\/2019) se distanciar\u00e1 ainda mais do hatch \u2013 at\u00e9 mesmo as portas traseiras ser\u00e3o exclusivas \u2013 e o HB20X (previs\u00e3o de lan\u00e7amento dia \u202a01\/12\/2019) ficar\u00e1 5 cm mais alto que o atual. Ambos chegam neste ano.<\/p>\n<\/article>\n<\/div>\n<div class=\"post-conteudo-imagem col-xs-12 no-padding\">\n<div class=\"col-xs-12 no-padding img-container\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/gmconline.com.br\/uploads\/8b26305349c8d333d5c6b697d29ccac4.png\" alt=\"Bloco de Imagem\" \/><\/div>\n<div class=\"col-xs-12 bg-cinza2\">O restante da fam\u00edlia tamb\u00e9m ser\u00e1 apresentada em breve: o novo HB20S (previs\u00e3o lan\u00e7amento \u202a01\/11\/2019) se distanciar\u00e1 ainda mais do hatch \u2013 at\u00e9 mesmo as portas traseiras ser\u00e3o exclusivas \u2013 e o HB20X (previs\u00e3o de lan\u00e7amento dia \u202a01\/12\/2019) ficar\u00e1 5 cm mais alto que o atual. Ambos chegam neste ano.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>O novo Hb-20, as v\u00e9speras do lan\u00e7amento das vendas no Brasil \u2013 com in\u00edcio esta semana, ter\u00e1 sua apresenta\u00e7\u00e3o antecipada nesta sexta-feira na Hyundai Lovat em<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":110,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,226],"tags":[],"class_list":["post-6852","post","type-post","status-publish","format-standard","hentry","category-clientes","category-hyundai"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=6852"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6852\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=6852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=6852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=6852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}