{"id":6776,"date":"2019-09-11T05:24:15","date_gmt":"2019-09-11T08:24:15","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=6776"},"modified":"2019-09-20T05:28:40","modified_gmt":"2019-09-20T08:28:40","slug":"governo-estadual-retira-antecipacao-de-imposto-sobre-alimentos-no-parana","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/governo-estadual-retira-antecipacao-de-imposto-sobre-alimentos-no-parana\/","title":{"rendered":"Governo estadual retira antecipa\u00e7\u00e3o de imposto sobre alimentos no Paran\u00e1"},"content":{"rendered":"<header class=\"titulo-pagina\">S\u00e3o 60 mil itens que deixam o regime de Substitui\u00e7\u00e3o Tribut\u00e1ria. Um dos objetivos \u00e9 aumentar a competitividade entre as empresas.<\/p>\n<\/header>\n<div class=\"conteudo\">\n<p>Na lista, mais de 60 mil produtos do setor de alimentos. Os vinhos tamb\u00e9m entraram na revis\u00e3o. Esses itens v\u00e3o deixar o regime de Substitui\u00e7\u00e3o Tribut\u00e1ria (ST). A mudan\u00e7a, por meio de um decreto, assinado pelo governador Ratinho Junior come\u00e7a a valer em 1\u00ba de novembro.<\/p>\n<p>A advogada tributarista Ligia Prado Rosolem explica que essa altera\u00e7\u00e3o na forma de arrecada\u00e7\u00e3o tende a ser positiva para a cadeia produtiva do Paran\u00e1 por restabelecer a competitividade das empresas, j\u00e1 que Santa Catarina, S\u00e3o Paulo e Rio Grande do Sul j\u00e1 implantaram essa pol\u00edtica.<\/p>\n<p>Ela explica que essa mudan\u00e7a significa que o fabricante deixa de destacar o valor do ICMS para o comerciante, que tamb\u00e9m n\u00e3o precisa mais pagar esse imposto de forma antecipada, antes de vender o produto, inclusive.<\/p>\n<p>No regime de Substitui\u00e7\u00e3o Tribut\u00e1ria, o valor da Margem de Valor Agregado (MVA) nem sempre \u00e9 obtido com a venda e gerava um tipo de tabelamento na cadeia. Na opini\u00e3o da advogada, o pagamento do ICMS sobre os produtos apenas na hora da venda por parte do comerciante ajuda tamb\u00e9m a deixar o valor mais preciso.<\/p>\n<p>O regime da Substitui\u00e7\u00e3o Tribut\u00e1ria \u00e9 usado por todos os 27 estados, mas vem sendo reduzido em alguns deles, o que gerou reclama\u00e7\u00f5es pela classe empresarial em rela\u00e7\u00e3o a perda de competitividade.<\/p>\n<\/div>\n<div class=\"item-por\"><a href=\"https:\/\/cbnlondrina.com.br\/materias\/governo-estadual-retira-antecipacao-de-imposto-sobre-alimentos-no-parana\">Por\u00a0<b>Claudia Lima<\/b><\/a><\/div>\n<div><\/div>\n<div><audio class=\"wp-audio-shortcode\" id=\"audio-6776-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/cbnlondrina.com.br\/uploads\/materia_audio\/47-CLAUDIA_gTvq5mR1V6frh0k.mp3?_=1\" \/><a href=\"https:\/\/cbnlondrina.com.br\/uploads\/materia_audio\/47-CLAUDIA_gTvq5mR1V6frh0k.mp3\">https:\/\/cbnlondrina.com.br\/uploads\/materia_audio\/47-CLAUDIA_gTvq5mR1V6frh0k.mp3<\/a><\/audio><\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o 60 mil itens que deixam o regime de Substitui\u00e7\u00e3o Tribut\u00e1ria. Um dos objetivos \u00e9 aumentar a competitividade entre as empresas. Na lista, mais de 60<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":110,"featured_media":4319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[160],"tags":[],"class_list":["post-6776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vilela-berbel-e-mitne"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=6776"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=6776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=6776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=6776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}