{"id":6488,"date":"2019-06-08T19:21:25","date_gmt":"2019-06-08T22:21:25","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=6488"},"modified":"2019-06-12T19:23:58","modified_gmt":"2019-06-12T22:23:58","slug":"louisee-rodrigues-da-cruz-boari-esteve-nos-ultimos-dias-em-londrina","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/louisee-rodrigues-da-cruz-boari-esteve-nos-ultimos-dias-em-londrina\/","title":{"rendered":"Louisee Rodrigues da Cruz Boari esteve nos \u00faltimos dias em Londrina"},"content":{"rendered":"<figure class=\"col-md-12 col-xs-12 mw-pad-0 mw-m-t-15 mw-m-b-15\">\n<div>Louisee Rodrigues da Cruz Boari esteve nos \u00faltimos dias em Londrina. Ela palestrou a alunos do Col\u00e9gio Maxi falando sobre sua experi\u00eancia profissional, especialmente na \u00e1rea de educa\u00e7\u00e3o. Atualmente ela \u00e9 consultora do Banco Mundial na \u00e1rea de educa\u00e7\u00e3o e j\u00e1 trabalhou como avaliadora educacional para o MEC e como analista de pol\u00edticas educacionais na Funda\u00e7\u00e3o Lemann. Bacharel em Rela\u00e7\u00f5es Internacionais pela Universidade de S\u00e3o Paulo, Louisee tem, no curr\u00edculo, est\u00e1gio na OEA (Organiza\u00e7\u00e3o dos Estados Americanos) em Washington, e no Centro Internacional de Pol\u00edticas para o Crescimento Inclusivo vinculado ao Pnud (Programa das Na\u00e7\u00f5es Unidas para o Desenvolvimento), e \u00e9 mestre em An\u00e1lise de Pol\u00edticas P\u00fablicas pelas Universidades de Maastricht, na Holanda, e pela Universidade das Na\u00e7\u00f5es Unidas. O registro \u00e9 especial para a FOLHA<\/div>\n<div><img decoding=\"async\" class=\"mw-fit-width mw-fit-height\" src=\"https:\/\/www.folhadelondrina.com.br\/img\/inline\/2940000\/FGD3G8_02942607_5.jpg\" alt=\"\" \/><\/div><figcaption class=\"mw-bottom-5-absolute mw-fit-width mw-bg-sw-2 fdl-c-white mw-pad-t-100 mw-pad-b-15 mw-pad-l-10 mw-pad-r-10 text-center\">| Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25.pdf\">Folha_de_Londrina(2019-06-08)_page25<\/a> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6490\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001.jpg\" alt=\"\" width=\"614\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001.jpg 614w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001-171x300.jpg 171w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001-582x1024.jpg 582w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6491\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001rec.jpg\" alt=\"\" width=\"1916\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001rec.jpg 1916w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001rec-800x451.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001rec-300x169.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-08_page25_page-0001rec-1024x577.jpg 1024w\" sizes=\"auto, (max-width: 1916px) 100vw, 1916px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Louisee Rodrigues da Cruz Boari esteve nos \u00faltimos dias em Londrina. Ela palestrou a alunos do Col\u00e9gio Maxi falando sobre sua experi\u00eancia profissional, especialmente na \u00e1rea<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,203],"tags":[],"class_list":["post-6488","post","type-post","status-publish","format-standard","hentry","category-clientes","category-colegio-maxi-londrina"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=6488"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6488\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=6488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=6488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=6488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}