{"id":6478,"date":"2019-06-04T18:56:12","date_gmt":"2019-06-04T21:56:12","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=6478"},"modified":"2019-06-06T19:00:00","modified_gmt":"2019-06-06T22:00:00","slug":"giro-das-profissoes-2","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/giro-das-profissoes-2\/","title":{"rendered":"Giro das profiss\u00f5es"},"content":{"rendered":"<p>O Col\u00e9gio Maxi promove o evento \u201cMaxi Momento:oriente!\u201d \u00c9 uma atividade que se repete todos os anos para que os alunos do ensino m\u00e9dio e pr\u00e9-vestibular possam conhecer mais, a partir de experi\u00eancias de profissionais e tamb\u00e9m acad\u00eamicos. De uma forma simples detalhada, eles t\u00eam acesso \u00e0s profiss\u00f5es que poder\u00e3o escolher, por meio do \u201cGiro das Profiss\u00f5es\u201d, em que os profissionais de cada \u00e1rea de atua\u00e7\u00e3o estar\u00e3o dispon\u00edveis para esclarecer d\u00favidas, a partir de um bate-papo at\u00e9 o atendimento individual. As atividades come\u00e7aram ontem, segunda-feira, e seguir\u00e3o durante a semana,com palestras ministradas por profissionais que ir\u00e3o contar a trajet\u00f3ria, conquistas e satisfa\u00e7\u00f5es da carreira.<\/p>\n<div><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-04_page18.pdf\">Folha_de_Londrina(2019-06-04)_page18<\/a> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6480\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/MaxiOriente.jpg\" alt=\"\" width=\"1817\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/MaxiOriente.jpg 1817w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/MaxiOriente-800x476.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/MaxiOriente-300x178.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/MaxiOriente-1024x609.jpg 1024w\" sizes=\"auto, (max-width: 1817px) 100vw, 1817px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6481\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-04_page18.jpg\" alt=\"\" width=\"594\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-04_page18.jpg 594w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-04_page18-165x300.jpg 165w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/06\/Folha_de_Londrina2019-06-04_page18-563x1024.jpg 563w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Col\u00e9gio Maxi promove o evento \u201cMaxi Momento:oriente!\u201d \u00c9 uma atividade que se repete todos os anos para que os alunos do ensino m\u00e9dio e pr\u00e9-vestibular<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":6406,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,203],"tags":[],"class_list":["post-6478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-colegio-maxi-londrina"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=6478"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/6406"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=6478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=6478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=6478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}