{"id":6334,"date":"2019-03-27T16:24:12","date_gmt":"2019-03-27T19:24:12","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=6334"},"modified":"2019-03-27T16:24:12","modified_gmt":"2019-03-27T19:24:12","slug":"espaco-aberto-filhos-e-o-senso-de-proposito","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/espaco-aberto-filhos-e-o-senso-de-proposito\/","title":{"rendered":"ESPA\u00c7O ABERTO &#8211; Filhos e o senso de prop\u00f3sito"},"content":{"rendered":"<p>A quest\u00e3o mais central e ao mesmo tempo menos esclarecida da exist\u00eancia humana \u00e9 a raz\u00e3o da vida e o que pode torn\u00e1-la feliz. Fil\u00f3sofos e te\u00f3logos tentam encontrar respostas h\u00e1 mais de tr\u00eas mil anos, mas ningu\u00e9m tem uma solu\u00e7\u00e3o definitiva. Por isso devemos respeito \u00e0 pluralidade de cren\u00e7as existentes e nos munir com humildade ao pensar e teorizar a respeito.<\/p>\n<p>Uma das minhas cren\u00e7as preferidas \u00e9 o senso de prop\u00f3sito. Atrav\u00e9s dela podemos acreditar que a vida com uma raz\u00e3o \u00e9 uma vida que vale a pena ser vivida! Sob essa \u00f3tica torna-se nossa responsabilidade a nossa pr\u00f3pria felicidade, quando definimos qual ser\u00e1 o prop\u00f3sito.<\/p>\n<p>Libertador e ao mesmo tempo amedrontador, pois a inseguran\u00e7a de atingir um objetivo ou d\u00favida sobre ter feito tudo o que era poss\u00edvel para conquist\u00e1-lo sempre estar\u00e1 rondando nossos pensamentos.<\/p>\n<p>A pergunta que naturalmente segue \u00e9: existe prop\u00f3sito-chave que pode trazer felicidade e raz\u00e3o para a maioria? Acredito que sim. Jesus nos ensinou amor ao pr\u00f3ximo, a isso chamamos \u00c1gape. Doar-se. Fazer a diferen\u00e7a na vida de algu\u00e9m, ou &#8220;algu\u00e9ns&#8221;.<\/p>\n<p>Gigantesca doa\u00e7\u00e3o \u00e9 ter filhos responsavelmente. Ceder seu corpo para algu\u00e9m que voc\u00ea ainda nem conhece. Nesse momento a m\u00e3e sente mais, descobre la\u00e7os e sentimentos que nunca se apagar\u00e3o. A m\u00e3e nasce na concep\u00e7\u00e3o, o pai \u00e9 gestado juntamente com a crian\u00e7a, nasce no parto do filho.<\/p>\n<p>Os primeiros anos s\u00e3o de entrega. Literalmente! Entrega-se o descanso, o sono, a tranquilidade, o trabalho&#8230; \u00c9 nesse momento que a entrega, quase que por m\u00e1gica, transforma-se em raz\u00e3o e prop\u00f3sito.<\/p>\n<p>A fragilidade do dependente agu\u00e7a ainda mais o amor natural. Tudo isso e mais um pouco transmuta o prop\u00f3sito em felicidade. N\u00e3o a felicidade do \u00eaxtase, ou do prazer moment\u00e2neo, mas a felicidade de sentir-se necess\u00e1rio e presente. Necessariamente presente.<\/p>\n<p>Trabalho h\u00e1 anos ajudando casais com dificuldades em ter filhos. A cada diagn\u00f3stico compartilho e vivo a dor dos pacientes, da mesma forma que divido com eles a esperan\u00e7a e f\u00e9 na efic\u00e1cia dos tratamentos.<\/p>\n<p>A dor do casal que n\u00e3o consegue engravidar \u00e9 a dor da aus\u00eancia, daquilo que deveria, mas n\u00e3o foi vivido. Da procura pelo prop\u00f3sito. Felizmente a medicina tem muitas op\u00e7\u00f5es, o que pode resolver muitos casos, al\u00e9m da linda solu\u00e7\u00e3o social que \u00e9 a ado\u00e7\u00e3o.<\/p>\n<p>Descubro o maior prazer que essa profiss\u00e3o pode trazer quando quase anonimamente, em algum parque ou shopping center, vejo, \u00e0 dist\u00e2ncia, casais previamente sem filhos, agora com seus pequenos.<\/p>\n<p>Consigo encontrar nos seus olhos algo que fil\u00f3sofos e te\u00f3logos procuram h\u00e1 mais de tr\u00eas mil anos, ali diante da nova presen\u00e7a que se criou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6335\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001r.jpg\" alt=\"\" width=\"636\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001r.jpg 636w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001r-177x300.jpg 177w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001r-603x1024.jpg 603w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6336\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001.jpg\" alt=\"\" width=\"598\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001.jpg 598w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001-166x300.jpg 166w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2_page-0001-567x1024.jpg 567w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2019\/03\/Folha_de_Londrina2019-03-27_page2.pdf\">Folha_de_Londrina(2019-03-27)_page2<\/a><\/p>\n<p><a href=\"https:\/\/www.folhadelondrina.com.br\/opiniao\/espaco-aberto---filhos-e-o-senso-de-proposito-2936771e.html\">Jo\u00e3o Guilherme Grassi, m\u00e9dico especialista em infertilidade<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A quest\u00e3o mais central e ao mesmo tempo menos esclarecida da exist\u00eancia humana \u00e9 a raz\u00e3o da vida e o que pode torn\u00e1-la feliz. Fil\u00f3sofos e<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[221,159],"tags":[],"class_list":["post-6334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centro-de-fertilidade-saab","category-clientes"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=6334"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/6334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4318"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=6334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=6334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=6334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}