{"id":5975,"date":"2018-11-14T18:35:46","date_gmt":"2018-11-14T21:35:46","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=5975"},"modified":"2018-11-19T18:36:57","modified_gmt":"2018-11-19T21:36:57","slug":"maxi-na-parceria-com-a-university-missouri","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/maxi-na-parceria-com-a-university-missouri\/","title":{"rendered":"Maxi na parceria com a University Missouri"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Col\u00e9gio Maxi promover\u00e1 hoje, dia 14, o High Scholl Experience, que ser\u00e1 um bate-papo com os professores sobre o Maxi High School. Trata-se de uma parceria com a University of Missouri, EUA, que oferece a estudantes, a partir do nono ano do Ensino Fundamental, ou da 1\u00aa s\u00e9rie do Ensino M\u00e9dio, a possibilidade de cursar o ensino m\u00e9dio americano no Brasil, com disciplinas oficiais do curr\u00edculo dos Estados Unidos, como orat\u00f3ria, pol\u00edtica, economia, hist\u00f3ria, literatura e reda\u00e7\u00e3o. O aluno do Maxi High School conclui o ensino m\u00e9dio recebendo dois diplomas: o do Col\u00e9gio Maxi &#8211; pelo ensino m\u00e9dio tradicional &#8211; e o da University of Missouri High School, aceito oficialmente em todas as universidades norte-americanas. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"469\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/0-1-1024x469.jpg\" alt=\"\" class=\"wp-image-5976\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/0-1-1024x469.jpg 1024w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/0-1-800x366.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/0-1-300x137.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/0-1.jpg 1061w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Col\u00e9gio Maxi promover\u00e1 hoje, dia 14, o High Scholl Experience, que ser\u00e1 um bate-papo com os professores sobre o Maxi High School. Trata-se de uma<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":5652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,203],"tags":[],"class_list":["post-5975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-colegio-maxi-londrina"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=5975"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/5652"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=5975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=5975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=5975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}