{"id":5970,"date":"2018-11-12T18:23:55","date_gmt":"2018-11-12T21:23:55","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=5970"},"modified":"2018-11-19T18:27:25","modified_gmt":"2018-11-19T21:27:25","slug":"professores-ressaltam-importancia-do-enem-para-acesso-a-universidade","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/professores-ressaltam-importancia-do-enem-para-acesso-a-universidade\/","title":{"rendered":"Professores ressaltam import\u00e2ncia do Enem para acesso \u00e0 universidade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Criado em 1998 pelo MEC (Minist\u00e9rio da Educa\u00e7\u00e3o) com o objetivo de avaliar o desempenho dos estudantes ao fim do ensino b\u00e1sico, o Enem (Exame Nacional do Ensino M\u00e9dio) passou por uma reformula\u00e7\u00e3o em 2009, quando ganhou car\u00e1ter de processo seletivo, e duas d\u00e9cadas depois se consolida como importante meio de acesso \u00e0s universidades do Pa\u00eds. Em diversas ocasi\u00f5es o exame teve sua lisura posta em xeque em meio a den\u00fancias de furtos e vazamentos de provas e erros de impress\u00e3o, mas educadores s\u00e3o un\u00e2nimes em reconhecer a relev\u00e2ncia do Enem. As provas do Enem foram realizadas em dois domingos &#8211; dias 4 e 11 de novembro. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Professora de reda\u00e7\u00e3o e gram\u00e1tica e coordenadora do Curso Prime Londrina, do Grupo Sigma, M\u00e1rcia Chir\u00e9ia considera o Enem uma poderosa ferramenta para mensurar o trabalho desenvolvido por alunos e professores ao longo dos tr\u00eas anos do ensino m\u00e9dio. &#8220;\u00c9 uma prova necess\u00e1ria no Brasil, foi um mal necess\u00e1rio porque olhou-se mais para a educa\u00e7\u00e3o a partir do Enem. A tend\u00eancia \u00e9 cada vez mais as universidades se utilizarem da prova para receber os alunos&#8221;, afirma. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chir\u00e9ia aposta em um aumento gradativo, nos pr\u00f3ximos anos, do n\u00famero de universidades que ir\u00e3o substituir os vestibulares pelo Enem. &#8220;N\u00e3o vai chegar a 100%, mas a maioria das vagas nas universidades ser\u00e1 pelo Enem em um futuro n\u00e3o muito distante. Hoje, a maioria das federais e boa parte das estaduais t\u00eam vagas para alunos do Enem&#8221;, ressaltou ela, sem deixar de lado as cr\u00edticas ao modelo de avalia\u00e7\u00e3o. &#8220;O principal objetivo do Enem \u00e9 medir as habilidades leitoras dos alunos e, naturalmente, as quest\u00f5es cobram bastante a interpreta\u00e7\u00e3o. Mas no meu ponto de vista, h\u00e1 enunciados demasiadamente longos que poderiam ser mais sucintos&#8221;, comentou. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A professora tamb\u00e9m v\u00ea aspectos negativos no modelo exigido de reda\u00e7\u00e3o. &#8220;A proposta de interven\u00e7\u00e3o, que \u00e9 o formato do Enem, prejudicou a escola. A maioria das escolas, hoje, n\u00e3o est\u00e1 preocupada em ensinar o aluno a escrever, mas a escrever a reda\u00e7\u00e3o do Enem. Elas se preocupam muito em ensinar um \u00fanico formato e tira um pouco do papel da escola que \u00e9 escrever para a vida e n\u00e3o para uma prova&#8221;, disse Chir\u00e9ia. &#8220;A reda\u00e7\u00e3o ficou muito mec\u00e2nica. O que talvez melhorasse um pouco seria o Enem deixar mais livre o formato da reda\u00e7\u00e3o&#8221;, opinou. &#8220;Mas eu vejo uma import\u00e2ncia gigante do Enem. Se n\u00e3o tivesse (o exame), estar\u00edamos em um quadro pior na educa\u00e7\u00e3o, porque est\u00e1 vergonhoso.&#8221; <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">MATEM\u00c1TICA <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Professor de matem\u00e1tica da Rede Maxi, de Londrina, Marco Antonio Velasco Capri destaca como ponto positivo no Enem a preocupa\u00e7\u00e3o em colocar as ci\u00eancias aplicadas a situa\u00e7\u00f5es cotidianas. &#8220;\u00c9 muito diferente dos vestibulares tradicionais, que tentam cercar os conte\u00fados do ensino m\u00e9dio. O Enem n\u00e3o tem isso. Eles tentam colocar uma matem\u00e1tica mais natural, mostrar que a matem\u00e1tica serve para as quest\u00f5es pr\u00e1ticas do dia a dia.&#8221; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na prova de matem\u00e1tica deste domingo (11), avaliou Capri, os alunos que utilizaram provas de concursos anteriores como treinamento certamente n\u00e3o tiveram dificuldade para resolver as quest\u00f5es e nem estranharam o conte\u00fado cobrado. &#8220;Algumas quest\u00f5es do Enem na matem\u00e1tica n\u00e3o s\u00e3o s\u00f3 de habilidade de c\u00e1lculo. Tem quest\u00f5es de no\u00e7\u00e3o de espa\u00e7o, orienta\u00e7\u00e3o, \u00e0s vezes \u00e9 s\u00f3 uma interpreta\u00e7\u00e3o de gr\u00e1fico, uma an\u00e1lise de tabela.&#8221; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Capri considera &#8220;fundamental&#8221; a realiza\u00e7\u00e3o do Enem. &#8220;H\u00e1 universidades de fora do Brasil usando o Enem. Eu, como professor de pr\u00e9-vestibular, vejo alunos abrindo m\u00e3o do vestibular para fazer o Enem porque v\u00ea possibilidades maiores de acesso \u00e0 universidade&#8221;, lembrou. No Brasil s\u00e3o 1.434 institui\u00e7\u00f5es que usam o Enem e em Portugal, 35. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na semana passada, ap\u00f3s pol\u00eamicas envolvendo duas quest\u00f5es da prova de linguagens, aplicada no primeiro dia do Enem, o presidente eleito Jair Bolsonaro chegou a declarar que a partir do pr\u00f3ximo ano pretende ter acesso \u00e0s quest\u00f5es antes da aplica\u00e7\u00e3o das provas. Para Chir\u00e9ia, as declara\u00e7\u00f5es configuram censura e demonstram desconhecimento acerca do exame. &#8220;O Enem \u00e9 extremamente sigiloso, pouqu\u00edssimas pessoas t\u00eam acesso \u00e0s quest\u00f5es selecionadas por cada banca. E a prova da semana passada tinha 90 quest\u00f5es. Apenas duas mencionavam alguma coisa em rela\u00e7\u00e3o \u00e0 quest\u00e3o de g\u00eanero. Acho interessante porque j\u00e1 caiu dialeto do futebol e ningu\u00e9m disse nada. Mas como a gente est\u00e1 vivendo um momento com \u00e2nimos exaltados, houve toda essa pol\u00eamica.&#8221; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente eleito, disse, durante a transmiss\u00e3o de cerca de 40 minutos feita nas redes sociais, que &#8220;No Enem do ano que vem, pode ter certeza, fique tranquilo, n\u00e3o vai ter press\u00e3o dessa forma no ano que vem. N\u00f3s vamos tomar conhecimento da prova antes. V\u00e3o ter perguntas sobre Geografia, disserta\u00e7\u00e3o sobre Hist\u00f3ria, quest\u00f5es voltadas ao que interessa ao futuro da nossa gera\u00e7\u00e3o, do nosso Brasil&#8221;, disse Bolsonaro, ao comentar uma das quest\u00f5es que tratou do pajub\u00e1, dialeto secreto de LGBTs. (Com Ag\u00eancia Estado)<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/Folha_de_Londrina2018-11-12_page6.pdf\">Folha_de_Londrina(2018-11-12)_page6<\/a><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/11\/Folha_de_Londrina2018-11-12_page6.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.folhadelondrina.com.br\/geral\/professores-ressaltam-importancia-do-enem-para-acesso-a-universidade-1020143.html\">Simoni Saris\/Reportagem Local<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Criado em 1998 pelo MEC (Minist\u00e9rio da Educa\u00e7\u00e3o) com o objetivo de avaliar o desempenho dos estudantes ao fim do ensino b\u00e1sico, o Enem (Exame Nacional<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,203],"tags":[],"class_list":["post-5970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-colegio-maxi-londrina"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=5970"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4318"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=5970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=5970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=5970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}