{"id":5565,"date":"2018-04-11T22:33:26","date_gmt":"2018-04-12T01:33:26","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=5565"},"modified":"2018-05-02T16:37:41","modified_gmt":"2018-05-02T19:37:41","slug":"na-expo-osmar-dias-desconversa-sobre-aliancas-para-eleicao-estadual","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/na-expo-osmar-dias-desconversa-sobre-aliancas-para-eleicao-estadual\/","title":{"rendered":"Na Expo, Osmar Dias desconversa sobre alian\u00e7as para elei\u00e7\u00e3o estadual"},"content":{"rendered":"<div align=\"center\">\n<div class=\"imagefmt\"><img decoding=\"async\" class=\"imgz\" title=\"Saulo Ohara\/Grupo Folha\" src=\"https:\/\/www.folhadelondrina.com.br\/img\/2018\/04\/img_2088.jpg\" alt=\"Saulo Ohara\/Grupo Folha\" \/><\/div>\n<\/div>\n<p>O pr\u00e9-candidato ao governo estadual pelo PDT em 2018, Osmar Dias afirmou nesta quarta-feira (11), durante visita na ExpoLondrina, que n\u00e3o est\u00e1 procurando alian\u00e7as partid\u00e1rias para o pleito de outubro. &#8220;Estou preocupado em elaborar um bom projeto para o Paran\u00e1. N\u00e3o corro atr\u00e1s de legendas para rechear a minha candidatura. Eu apenas coloco o planejamento na mesa, e aqueles que aceitarem as propostas ser\u00e3o bem-vindos. Tem que ser do meu jeito&#8221;, frisou.<\/p>\n<p>Para Dias, &#8220;o Paran\u00e1 tem muitas oportunidades de crescimento que n\u00e3o est\u00e3o sendo aproveitadas&#8221;. E \u00e9 com base neste conceito que o pedetista assegura ter desenvolvido suas ideias. &#8220;N\u00e3o nego o meu passado. J\u00e1 trabalhei para o agroneg\u00f3cio, agora pretendo fomentar a parte urbana&#8221;. Em uma clara refer\u00eancia \u00e0 gest\u00e3o Beto Richa, que deixou o Pal\u00e1cio do Igua\u00e7u no final de mar\u00e7o para concorrer ao Senado, ele citou que &#8220;n\u00e3o aprova o modelo atual de administra\u00e7\u00e3o. Felizmente que isso est\u00e1 acabando&#8221;, opinou.<\/p>\n<p>Apesar de militar no PDT, Osmar Dias garantiu que ir\u00e1 apoiar o irm\u00e3o, o senador \u00c1lvaro Dias (Podemos), j\u00e1 confirmado como candidato \u00e0 Presid\u00eancia da Rep\u00fablica. &#8220;Sou e continuarei a ser leal a ele. Esse assunto j\u00e1 foi superado com a Executiva nacional. Reitero que n\u00e3o colocarei na mesa essa negocia\u00e7\u00e3o entre os partidos e pol\u00edticos&#8221;. O pedetista tamb\u00e9m foi enf\u00e1tico quando questionado sobre o resultado da pesquisa do Ibope Intelig\u00eancia, que mediu a inten\u00e7\u00e3o de voto para o governo estadual. &#8220;Os outros dois (Cida Borghetti, do PP, e Ratinho J\u00fanior, PSD) s\u00e3o candidatos h\u00e1 sete anos. Mesmo assim, gostei da receptividade dos eleitores&#8221;.<\/p>\n<p>O levantamento mostra que Ratinho Jr. aparece em primeiro lugar, com 34%, seguido pelo pr\u00f3prio Osmar, que aparece com 28%.<\/p>\n<p>Presidenci\u00e1vel<\/p>\n<p>Ainda nesta quarta, o candidato ao Planalto pelo Partido NOVO, o empres\u00e1rio Jo\u00e3o Amo\u00eado, veio a Londrina conversar com lideran\u00e7as pol\u00edticas e empresariais para apresentar suas propostas. O partido foi fundado em fevereiro de 2011 por 181 cidad\u00e3os de 35 profiss\u00f5es diferentes que nunca exerceram mandato pol\u00edtico. O lema \u00e9 a defesa intransigente de que o caminho para melhorar a qualidade de vida das pessoas \u00e9 por meio da liberdade com responsabilidade. A legenda \u00e9 representada pelo n\u00famero 30. Em sua primeira elei\u00e7\u00e3o (a municipal de 2016), concorreu em cinco capitais e conseguiu eleger vereadores em S\u00e3o Paulo, Rio de Janeiro, Porto Alegre e Belo Horizonte.<\/p>\n<p>(com informa\u00e7\u00f5es do rep\u00f3rter Guilherme Marconi, da Folha de Londrina)<br \/>\n<a href=\"https:\/\/www.folhadelondrina.com.br\/politica\/na-expo-osmar-dias-desconversa-sobre-aliancas-para-eleicao-estadual-1004342.html\">Rafael Machado<\/a><br \/>\n<a href=\"https:\/\/www.folhadelondrina.com.br\/politica\/na-expo-osmar-dias-desconversa-sobre-aliancas-para-eleicao-estadual-1004342.html\">Grupo Folha<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pr\u00e9-candidato ao governo estadual pelo PDT em 2018, Osmar Dias afirmou nesta quarta-feira (11), durante visita na ExpoLondrina, que n\u00e3o est\u00e1 procurando alian\u00e7as partid\u00e1rias para<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,202],"tags":[],"class_list":["post-5565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-partido-novo"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=5565"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4318"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=5565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=5565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=5565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}