{"id":5562,"date":"2018-04-11T22:32:49","date_gmt":"2018-04-12T01:32:49","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=5562"},"modified":"2018-05-02T16:37:41","modified_gmt":"2018-05-02T19:37:41","slug":"joao-amoedo-do-partido-novo-na-cidade","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/joao-amoedo-do-partido-novo-na-cidade\/","title":{"rendered":"Jo\u00e3o Amo\u00eado, do Partido Novo, na cidade"},"content":{"rendered":"<p>O empres\u00e1rio Jo\u00e3o Amo\u00eado, pr\u00e9-candidato do Partido Novo \u00e0 presid\u00eancia da Rep\u00fablica, estar\u00e1 em Londrina hoje. Vem participar de evento em que ser\u00e1 debatido a renova\u00e7\u00e3o da pol\u00edtica brasileira, a necessidade de modernizar o Estado, e acabar com privil\u00e9gios, al\u00e9m de colocar o cidad\u00e3o como protagonista dessa mudan\u00e7a. O encontro ser\u00e1 durante almo\u00e7o no Buffet Elite, onde participar\u00e3o, por ades\u00e3o, lideran\u00e7as politicas e empresariais locais e simpatizantes das ideias liberais. O Novo \u00e9 o partido que vem crescendo bastante no pa\u00eds e que vem demonstrando a sua influ\u00eancia nas redes sociais. O partido lan\u00e7ar\u00e1 candidatos a senadores e deputados federais em 18 estados e no distrito federal. Disputar\u00e1 tamb\u00e9m os governos estaduais de S\u00e3o Paulo, Minas Gerais, Bras\u00edlia, Rio Grande do Sul e Rio de Janeiro. <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5563\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina18-1.jpg\" alt=\"\" width=\"590\" height=\"1080\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina18-1.jpg 590w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina18-1-164x300.jpg 164w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina18-1-559x1024.jpg 559w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O empres\u00e1rio Jo\u00e3o Amo\u00eado, pr\u00e9-candidato do Partido Novo \u00e0 presid\u00eancia da Rep\u00fablica, estar\u00e1 em Londrina hoje. Vem participar de evento em que ser\u00e1 debatido a renova\u00e7\u00e3o<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,202],"tags":[],"class_list":["post-5562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-partido-novo"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=5562"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4318"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=5562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=5562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=5562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}