{"id":5554,"date":"2018-04-12T22:26:31","date_gmt":"2018-04-13T01:26:31","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=5554"},"modified":"2018-05-02T16:37:41","modified_gmt":"2018-05-02T19:37:41","slug":"encontro-de-liberais","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/encontro-de-liberais\/","title":{"rendered":"Encontro de liberais"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5571\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina3-1-Large.jpg\" alt=\"\" width=\"1050\" height=\"1920\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina3-1-Large.jpg 1050w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina3-1-Large-800x1463.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina3-1-Large-164x300.jpg 164w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2018\/04\/pagina3-1-Large-560x1024.jpg 560w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><\/p>\n<p>O presidenci\u00e1vel Jo\u00e3o Amo\u00eado, pr\u00e9-candidato pelo partido NOVO, confirmou sua vinda \u00e0 ExpoLondrina. Ele participa de um evento em que vai discutir a renova\u00e7\u00e3o da pol\u00edtica brasileira, da necessidade de modernizar o Estado, acabar com os privil\u00e9gios e colocar o cidad\u00e3o como protagonista dessa mudan\u00e7a. O encontro ser\u00e1 em um almo\u00e7o no buffet Elite, onde participam por ades\u00e3o lideran\u00e7as pol\u00edticas e empresariais locais e simpatizantes das ideias liberais. Al\u00e9m da Presid\u00eancia, o partido NOVO lan\u00e7ar\u00e1 candidatos a deputado federal e senadores em 18 estados, al\u00e9m do Distrito Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidenci\u00e1vel Jo\u00e3o Amo\u00eado, pr\u00e9-candidato pelo partido NOVO, confirmou sua vinda \u00e0 ExpoLondrina. Ele participa de um evento em que vai discutir a renova\u00e7\u00e3o da pol\u00edtica<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,202],"tags":[],"class_list":["post-5554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-partido-novo"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=5554"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4318"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=5554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=5554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=5554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}