{"id":5468,"date":"2018-03-06T17:51:17","date_gmt":"2018-03-06T20:51:17","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=5468"},"modified":"2018-03-07T17:52:20","modified_gmt":"2018-03-07T20:52:20","slug":"mutirao-de-cirurgias-de-catarata-atendera-15-mil-em-londrina","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/mutirao-de-cirurgias-de-catarata-atendera-15-mil-em-londrina\/","title":{"rendered":"Mutir\u00e3o de cirurgias de catarata atender\u00e1 1,5 mil em Londrina"},"content":{"rendered":"<p>O mutir\u00e3o de cirurgias eletivas de catarata vai atender 1,5 mil pessoas em Londrina ainda neste ano. Trezentas pessoas j\u00e1 passaram pelo procedimento neste s\u00e1bado (3) no Hospital de Olhos Hoftalon. O objetivo \u00e9 zerar a fila de espera no munic\u00edpio. Est\u00e3o envolvidos 35 profissionais, entre m\u00e9dicos e equipe t\u00e9cnica. A Secretaria de Estado da Sa\u00fade (Sesa) apoia viabilizando recursos e tamb\u00e9m com a doa\u00e7\u00e3o de equipamentos para a triagem de pacientes.<\/p>\n<p>&#8220;A amplia\u00e7\u00e3o das cirurgias de catarata em regime de mutir\u00e3o tem se mostrado uma estrat\u00e9gia importante para reduzir o tempo de espera pelo procedimento em todo Paran\u00e1. Em algumas regi\u00f5es a fila foi zerada e \u00e9 isso que pretendemos fazer em Londrina&#8221;, disse Caputo Neto.<\/p>\n<p>&#8220;A parceria com o Estado foi essencial para organizar a estrutura do mutir\u00e3o. O investimento e disponibiliza\u00e7\u00e3o dos aparelhos permitiram uma extens\u00e3o do alcance de p\u00fablico que n\u00e3o seria poss\u00edvel apenas com recursos pr\u00f3prios&#8221;, disse o superintendente administrativo e organizador do evento, Adriano Antunes.<\/p>\n<div id=\"sc-ava-82745895\">\u00a0V\u00e2nia Teixeira da Silva foi uma das pacientes atendidas no s\u00e1bado. A aposentada conta que j\u00e1 fez o procedimento no olho direito h\u00e1 alguns anos e agora precisa tratar o olho esquerdo. &#8220;D\u00f3i bastante e atrapalha muito minha rotina. Estou feliz de participar desse mutir\u00e3o gratuito&#8221;, diz. Ela tamb\u00e9m falou sobre os servi\u00e7os prestados na rede de sa\u00fade p\u00fablica. &#8220;Os profissionais nos atendem muito bem, s\u00e3o carinhosos e atenciosos&#8221;, acrescenta V\u00e2nia.<\/p>\n<\/div>\n<div align=\"center\">\n<div class=\"imagefmt\">\n<div class=\"e8 center\">AEN-PR<\/div>\n<p><img decoding=\"async\" class=\"imgz\" title=\"AEN-PR\" src=\"https:\/\/www.bonde.com.br\/img\/bondenews\/2018\/03\/img_1_27_1015.jpg\" alt=\"AEN-PR\" \/><\/div>\n<\/div>\n<p><b>Mutir\u00e3o<\/b>\u00a0\u2013 Desde 2015, o Governo do Estado destinou cerca de R$ 65 milh\u00f5es para o Mutir\u00e3o Paranaense de Cirurgias Eletivas. S\u00e3o procedimentos n\u00e3o emergenciais, mas que muitas vezes determinam a qualidade de vida de quem aguarda o atendimento.<\/p>\n<p>Mais de 70 mil procedimentos j\u00e1 ocorreram, com destaque para cirurgias de catarata, que j\u00e1 ultrapassam 35 mil em sistema de mutir\u00e3o. Desde 2017, os mutir\u00f5es s\u00e3o promovidos com recursos estaduais e federais. &#8220;Al\u00e9m de liberar recursos para os mutir\u00f5es, ano a ano a Secretaria da Sa\u00fade tem ampliado os n\u00fameros de procedimentos eletivos em todo Estado. De 2011 a 2017 ampliamos em 78% as cirurgias n\u00e3o emergenciais&#8221;, destacou o secret\u00e1rio<\/p>\n<p>Em 2011, houve 227 mil cirurgias eletivas no Paran\u00e1 \u2013 115 mil ambulatoriais e 112 mil hospitalares. Em 2017, o n\u00famero subiu para 404 mil cirurgias eletivas: 278 mil ambulatoriais e 126 mil hospitalares.<\/p>\n<div class=\"credito\"><a href=\"https:\/\/www.bonde.com.br\/saude\/noticias\/mutirao-de-cirurgias-de-catarata-atendera-1-5-mil-em-londrina-457493.html\">Fonte<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O mutir\u00e3o de cirurgias eletivas de catarata vai atender 1,5 mil pessoas em Londrina ainda neste ano. Trezentas pessoas j\u00e1 passaram pelo procedimento neste s\u00e1bado (3)<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4451,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,173],"tags":[],"class_list":["post-5468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-hoftalon"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=5468"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/5468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4451"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=5468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=5468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=5468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}