{"id":4650,"date":"2017-05-18T17:19:34","date_gmt":"2017-05-18T20:19:34","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=4650"},"modified":"2017-05-22T17:19:43","modified_gmt":"2017-05-22T20:19:43","slug":"hoftalon-promove-edicao-do-projeto-glaucoma","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/hoftalon-promove-edicao-do-projeto-glaucoma\/","title":{"rendered":"Hoftalon promove edi\u00e7\u00e3o do Projeto Glaucoma"},"content":{"rendered":"<p>O Hospital de Olhos de Londrina promove no pr\u00f3ximo s\u00e1bado (20), mais uma edi\u00e7\u00e3o do Projeto Glaucoma que completa 11 anos e que tem como objetivo informar a popula\u00e7\u00e3o e realizar exames gratuitos para diagn\u00f3stico da doen\u00e7a. O projeto, j\u00e1 atendeu mais de quatro mil pessoas, isso porque o Glaucoma est\u00e1 entre as doen\u00e7as oculares que mais preocupa a humanidade, provocando casos de cegueira irrevers\u00edveis.<\/p>\n<p>A doen\u00e7a \u00e9 causada principalmente pela eleva\u00e7\u00e3o da press\u00e3o intraocular que provoca les\u00f5es no nervo \u00f3tico e, como consequ\u00eancia, comprometimento visual. Se n\u00e3o for tratado adequadamente, pode levar \u00e0 cegueira. Rui Schimit, m\u00e9dico oftalmologista e presidente da comiss\u00e3o de resid\u00eancia m\u00e9dica do Hoftalon, falou da doen\u00e7a que, no Paran\u00e1, j\u00e1 atinge mais de 60 mil pessoas com mais de 40 anos de idade.<\/p>\n<p>Em 2016 foram avaliadas 330 pessoas, sendo que 83 foram encaminhadas com diagn\u00f3stico de glaucoma (25%). No evento de s\u00e1bado, ser\u00e3o distribu\u00eddas senhas a partir das 9 horas em frente \u00e0 entrada do Royal Plaza Shopping, na rua Mato Grosso, 310. Os exames ser\u00e3o realizados das 10 \u00e0s 12h30 no terceiro piso do shopping, anexo \u00e0 pra\u00e7a de alimenta\u00e7\u00e3o. Ser\u00e3o colocadas 200 cadeiras para todo o processo.<\/p>\n<p><a href=\"https:\/\/novo.paiquere.com.br\/hoftalon-promove-edicao-do-projeto-glaucoma\/#.WSNHfmjyskl\" target=\"_blank\" rel=\"noopener noreferrer\">Reda\u00e7\u00e3o Paiquer\u00ea\/Neto Almeida<\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-4650-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/novo.paiquere.com.br\/wp-content\/uploads\/2017\/05\/rui-01.mp3?_=1\" \/><a href=\"https:\/\/novo.paiquere.com.br\/wp-content\/uploads\/2017\/05\/rui-01.mp3\">https:\/\/novo.paiquere.com.br\/wp-content\/uploads\/2017\/05\/rui-01.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital de Olhos de Londrina promove no pr\u00f3ximo s\u00e1bado (20), mais uma edi\u00e7\u00e3o do Projeto Glaucoma que completa 11 anos e que tem como objetivo<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4441,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,173],"tags":[],"class_list":["post-4650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-hoftalon"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/4650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=4650"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/4650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4441"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=4650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=4650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=4650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}