{"id":4415,"date":"2017-03-24T22:08:24","date_gmt":"2017-03-25T01:08:24","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=4415"},"modified":"2017-03-24T22:08:46","modified_gmt":"2017-03-25T01:08:46","slug":"assessoria-de-imprensa-vilela-berbel-e-mitne-terceirizacao-advogado-explica-mudancas-praticas-para-o-trabalhador","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/assessoria-de-imprensa-vilela-berbel-e-mitne-terceirizacao-advogado-explica-mudancas-praticas-para-o-trabalhador\/","title":{"rendered":"Assessoria de Imprensa &#8211; Vilela Berbel e Mitne: Terceiriza\u00e7\u00e3o: advogado explica mudan\u00e7as pr\u00e1ticas para o trabalhador"},"content":{"rendered":"<p>Terceiriza\u00e7\u00e3o: advogado explica mudan\u00e7as pr\u00e1ticas para o trabalhador &#8220;Mais trabalho&#8221;, opina o especialista.<\/p>\n<p>A C\u00e2mara aprovou nessa quarta-feira (22), o projeto que prev\u00ea a terceiriza\u00e7\u00e3o irrestrita para contrata\u00e7\u00e3o de m\u00e3o de obra. O projeto permite que as empresas contratem trabalhadores terceirizados para atividades-meio e para as atividades-fim. Agora, o projeto segue para a san\u00e7\u00e3o do Presidente Temer.<\/p>\n<p>O Jornal Tarob\u00e1 conversou com o o advogado Gustavo Rezende Mitne, para esclarecer as mudan\u00e7as pr\u00e1ticas dessa decis\u00e3o hist\u00f3rica. \u201cO empregador ficava receoso em contratar m\u00e3o-de-obra. Hoje, ele consegue contratar mais com a lei da terceiriza\u00e7\u00e3o e ter mais rotatividade, mais colaboradores trabalhando na atividade terceirizada\u201d, opina Mitne.<\/p>\n<p>Assista \u00e0 entrevista completa:<\/p>\n<p><iframe loading=\"lazy\" title=\"C\u00e2mara aprova projeto para terceiriza\u00e7\u00e3o irrestrita de m\u00e3o de obra\" width=\"1220\" height=\"686\" src=\"https:\/\/www.youtube.com\/embed\/RbvOukLeYU4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Reda\u00e7\u00e3o, com Jornal Tarob\u00e1<\/p>\n<p>Fonte: <a href=\"https:\/\/www.tarobalondrina.com.br\/secoes\/2017\/03\/terceirizacao-advogado-explica-mudancas-praticas-para-o-trabalhador\/\">https:\/\/www.tarobalondrina.com.br\/secoes\/2017\/03\/terceirizacao-advogado-explica-mudancas-praticas-para-o-trabalhador\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terceiriza\u00e7\u00e3o: advogado explica mudan\u00e7as pr\u00e1ticas para o trabalhador &#8220;Mais trabalho&#8221;, opina o especialista. A C\u00e2mara aprovou nessa quarta-feira (22), o projeto que prev\u00ea a terceiriza\u00e7\u00e3o irrestrita<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":108,"featured_media":4295,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[160,159],"tags":[],"class_list":["post-4415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vilela-berbel-e-mitne","category-clientes"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/4415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=4415"}],"version-history":[{"count":0,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/4415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4295"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=4415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=4415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=4415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}