{"id":13635,"date":"2022-11-11T16:40:27","date_gmt":"2022-11-11T19:40:27","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?p=13635"},"modified":"2022-11-14T17:54:23","modified_gmt":"2022-11-14T20:54:23","slug":"projeto-de-lei-preve-aumento-de-recursos-para-o-hospital-evangelico-e-santa-casa","status":"publish","type":"post","link":"https:\/\/www.inovelondrina.com.br\/agencia\/projeto-de-lei-preve-aumento-de-recursos-para-o-hospital-evangelico-e-santa-casa\/","title":{"rendered":"Projeto de lei prev\u00ea aumento de recursos para o Hospital Evang\u00e9lico e Santa Casa"},"content":{"rendered":"<h4 style=\"font-weight: 600\">Projeto de lei prev\u00ea aumento de recursos para o Hospital Evang\u00e9lico e Santa Casa<\/h4>\n<p><span style=\"font-weight: 500\">\u00a011\/11\/22 \u00e0s 16:40\u00a0&#8211; Escrito por Reda\u00e7\u00e3o Tarob\u00e1 News<\/span><\/p>\n<p style=\"font-weight: 500\">Compartilhe<\/p>\n<p style=\"font-weight: inherit\">A Secretaria de Estado da Sa\u00fade do Paran\u00e1 (Sesa) informou que trabalha em um projeto de lei (PL) que prev\u00ea um aumento no repasse de recursos financeiros para o Hospital Evang\u00e9lico e Santa Casa de Londrina. O an\u00fancio foi feito em uma reuni\u00e3o\u00a0do Comit\u00ea de Crise da Sa\u00fade, realizada na manh\u00e3 desta sexta-feira (11), em Londrina.<\/p>\n<p style=\"font-weight: inherit\">Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre os valores e data de recebimento. A proposta\u00a0deve ser enviada \u00e0 Assembleia Legislativa ainda este m\u00eas, para vota\u00e7\u00e3o at\u00e9 o fim do ano.<\/p>\n<p style=\"font-weight: inherit\">Com o recurso extra, a expectativa \u00e9 que o Evang\u00e9lico mantenha o atendimento \u00e0s gestantes de alto risco, evitando que o Hospital Universit\u00e1rio (HU) tenha que assumir essa demanda.<\/p>\n<p style=\"font-weight: inherit\">O Comit\u00ea de Crise da Sa\u00fade foi formado ap\u00f3s convoca\u00e7\u00e3o pelo\u00a0Minist\u00e9rio P\u00fablico (MP) para discuss\u00e3o de problemas urgentes dos hospitais terci\u00e1rios do munic\u00edpio, que tamb\u00e9m atendem a regi\u00e3o. O grupo \u00e9 composto por\u00a0diretores das unidades, prefeitos da regi\u00e3o, secret\u00e1rios de sa\u00fade e pol\u00edticos.<\/p>\n<p style=\"font-weight: inherit\">Conforme o MP, as demandas est\u00e3o &#8220;muito al\u00e9m da capacidade instalada de servi\u00e7os&#8221;, al\u00e9m disso, as unidades afirmam d\u00e9ficit do or\u00e7amento.<\/p>\n<p style=\"font-weight: inherit\">O HU ainda aguarda um posicionamento do Estado sobre a manuten\u00e7\u00e3o dos 140 leitos ampliados durante a pandemia.\u00a0Os recursos est\u00e3o garantidos at\u00e9 dezembro, por\u00e9m a unidade planeja utilizar parte da capacidade para a implanta\u00e7\u00e3o da maternidade.<\/p>\n<p style=\"font-weight: inherit\">Recentemente, o\u00a0<b><a href=\"https:\/\/tarobanews.com\/noticias\/educacao\/hospital-universitario-retifica-edital-e-reajusta-valores-da-hora-de-trabalho-de-anestesistas\">Tribunal de Contas do Estado (TCE) autorizou um reajuste na hora de trabalho de m\u00e9dicos anestesistas no HU<\/a><\/b>. O objetivo \u00e9 atrair esse profissional para suprir a demanda na unidade, que no \u00faltimo m\u00eas, suspendeu\u00a0mais de 300 cirurgias eletivas por conta da falta de anestesistas.<\/p>\n<p><a href=\"https:\/\/tarobanews.com\/noticias\/ciencia-e-saude\/projeto-de-lei-preve-aumento-de-recursos-para-o-hospital-evangelico-e-santa-casa\">https:\/\/tarobanews.com\/noticias\/ciencia-e-saude\/projeto-de-lei-preve-aumento-de-recursos-para-o-hospital-evangelico-e-santa-casa<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Projeto de lei prev\u00ea aumento de recursos para o Hospital Evang\u00e9lico e Santa Casa \u00a011\/11\/22 \u00e0s 16:40\u00a0&#8211; Escrito por Reda\u00e7\u00e3o Tarob\u00e1 News Compartilhe A Secretaria de<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":5251,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[159,171],"tags":[],"class_list":["post-13635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clientes","category-hospital-evangelico"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/13635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=13635"}],"version-history":[{"count":2,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/13635\/revisions"}],"predecessor-version":[{"id":13637,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/posts\/13635\/revisions\/13637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/5251"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=13635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=13635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/tags?post=13635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}