{"id":3850,"date":"2016-07-26T14:37:35","date_gmt":"2016-07-26T17:37:35","guid":{"rendered":"https:\/\/www.inovelondrina.com.br\/agencia\/?post_type=portfolio&#038;p=3850"},"modified":"2018-12-14T15:29:46","modified_gmt":"2018-12-14T18:29:46","slug":"assessoria-de-imprensa-instituto-pontello","status":"publish","type":"portfolio","link":"https:\/\/www.inovelondrina.com.br\/agencia\/comunicacao-em-londrina\/assessoria-de-imprensa-instituto-pontello\/","title":{"rendered":"Assessoria de Imprensa  Instituto Pontello"},"content":{"rendered":"<p><strong>Folha de Londrina<br \/>\n<\/strong><em>segunda-feira, 2\u00a0de mar\u00e7o de 2017<br \/>\n<\/em><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Social-Folha-de-Londrina-02022017.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4329 size-thumbnail\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Social-Folha-de-Londrina-02022017-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong>Folha de Londrina<br \/>\n<\/strong><em>segunda-feira, 5 de dezembro de 2016<br \/>\n<\/em>Calv\u00edcie feminina precisa ser tratada precocemente<\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Calv%C3%ADcie-feminina-precisa-ser-tratada-precocemente.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4308\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Graphicloads-Filetype-Pdf.png\" alt=\"Graphicloads-Filetype-Pdf\" width=\"97\" height=\"97\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Calv\u00edcie-feminina-precisa-ser-tratada-precocemente.pdf\">Calv\u00edcie feminina precisa ser tratada precocemente<\/a><\/p>\n<hr \/>\n<p><strong>TV Tarob\u00e1<\/strong><\/p>\n<p>Vitrine Revista &#8211; Janeiro de 2017<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"96\" height=\"96\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 96px) 100vw, 96px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Estrias 01\/02\/2017<\/strong><\/p>\n<p><a href=\"https:\/\/youtu.be\/PoWXvYlcjWM\">https:\/\/youtu.be\/PoWXvYlcjWM<\/a><\/p>\n<p><iframe loading=\"lazy\" title=\"Estrias sem ou n\u00e3o sai?? Como??\" width=\"1220\" height=\"686\" src=\"https:\/\/www.youtube.com\/embed\/PoWXvYlcjWM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><strong>O que tem de mais moderno para o combate da flacidez \u00a002\/02\/2017<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Como reduzir a flacidez?\" width=\"1220\" height=\"686\" src=\"https:\/\/www.youtube.com\/embed\/XRNS4MwJRk8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gordura Localizada \u00a0 03\/01\/2017<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Gordura localizada sai ou n\u00e3o sai??\" width=\"1220\" height=\"686\" src=\"https:\/\/www.youtube.com\/embed\/GSEqEVjrjTM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<hr \/>\n<p>Folha de Londrina<\/p>\n<p>01\/01\/2017<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4298\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-10012017-196x300.jpg\" alt=\"Folha 10012017\" width=\"196\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-10012017-196x300.jpg 196w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-10012017.jpg 669w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>Folha de Londrina<\/p>\n<p>25 de novembro de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4297\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-25112016-216x300.jpg\" alt=\"folha-de-londrina-25112016\" width=\"216\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-25112016-216x300.jpg 216w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-25112016.jpg 736w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/p>\n<p><a href=\"https:\/\/www.folhadelondrina.com.br\/cidades\/exames-gratuitos-no-dia-de-combate-ao-cancer-de-pele-963943.html\">Acesse o link<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>RPCTV &#8211; Segunda edi\u00e7\u00e3o<\/p>\n<p>26 de novembro de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4225\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/10\/gdCnHsYD_400x400-300x300.jpg\" alt=\"gdCnHsYD_400x400\" width=\"105\" height=\"105\" \/><\/p>\n<p><a href=\"https:\/\/g1.globo.com\/pr\/norte-noroeste\/paranatv-2edicao\/videos\/t\/londrina\/v\/campanha-alerta-para-os-perigos-do-cancer-de-pele\/5477227\/\">Acesse o link\u00a0<\/a><\/p>\n<hr \/>\n<p>TV Tarob\u00e1 &#8211; Band<\/p>\n<p>26 de novembro de 2016<\/p>\n<p>Segunda\u00a0edi\u00e7\u00e3o<\/p>\n<p>HC realiza campanha de preven\u00e7\u00e3o de tratamento ao c\u00e2ncer de pele<\/p>\n<div id=\"watch7-headline\" class=\"clearfix\">\n<div id=\"watch-headline-title\">\n<h1 class=\"watch-title-container\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"106\" height=\"106\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 106px) 100vw, 106px\" \/><\/h1>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=1r7atTOvLGc\">Acesse o link<\/a><\/p>\n<\/div>\n<\/div>\n<hr \/>\n<p>RPCTV &#8211; Primeira edi\u00e7\u00e3o<\/p>\n<p>26 de novembro de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4225\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/10\/gdCnHsYD_400x400-300x300.jpg\" alt=\"gdCnHsYD_400x400\" width=\"114\" height=\"114\" \/><\/p>\n<p><a href=\"https:\/\/g1.globo.com\/pr\/parana\/paranatv-2edicao\/videos\/t\/londrina\/v\/campanha-alerta-para-os-perigos-do-cancer-de-pele\/5477227\/\">Acesse o link<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>TV Tarob\u00e1 &#8211; Band<\/p>\n<p>26 de novembro de 2016<\/p>\n<p>Primeira edi\u00e7\u00e3o<\/p>\n<p>HC realiza campanha de preven\u00e7\u00e3o de tratamento ao c\u00e2ncer de pele<\/p>\n<div id=\"watch7-headline\" class=\"clearfix\">\n<div id=\"watch-headline-title\">\n<h1 class=\"watch-title-container\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"106\" height=\"106\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 106px) 100vw, 106px\" \/><\/h1>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=1r7atTOvLGc\">Acesse o link<\/a><\/p>\n<hr \/>\n<\/div>\n<p>Tv Tarob\u00e1 &#8211; segunda edi\u00e7\u00e3o<\/p>\n<p>25 de novembro de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"136\" height=\"136\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 136px) 100vw, 136px\" \/><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=4RMfTTpMsXk\">Acesse o link<\/a><\/p>\n<\/div>\n<div id=\"watch7-user-header\" class=\" spf-link \"><\/div>\n<hr \/>\n<p>RPCTV 1\u00aa Edi\u00e7\u00e3o<\/p>\n<p>19 de novembro de 2016<\/p>\n<p>Sol, Calor e c\u00e2ncer de pele: \u00e9 preciso cuidado e prote\u00e7\u00e3o<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4225\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/10\/gdCnHsYD_400x400-300x300.jpg\" alt=\"gdCnHsYD_400x400\" width=\"99\" height=\"99\" \/><\/p>\n<p><a href=\"https:\/\/g1.globo.com\/pr\/parana\/paranatv-1edicao\/videos\/t\/londrina\/v\/sol-calor-e-cancer-de-pele-e-preciso-cuidado-e-protecao\/5455270\/\">Acesse o link<\/a><\/p>\n<h1><\/h1>\n<hr \/>\n<p>TV Taroba<\/p>\n<p>Programa Vitrine Revista com Lu Oliveira<\/p>\n<p>18 de novembro de 2016<\/p>\n<p>Manchas de Pele<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"127\" height=\"127\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 127px) 100vw, 127px\" \/><\/p>\n<p><a href=\"https:\/\/youtu.be\/zfAt6UNe7gY\">Acesse o link\u00a0<\/a><\/p>\n<hr \/>\n<p>TV Tarob\u00e1<\/p>\n<p>Programa Vitrine Revista com Lu Oliveira<\/p>\n<p>24\u00a0de outubro de 2016<\/p>\n<p>Mitos e verdades sobre estrias<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"140\" height=\"140\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=79hviKtChms&amp;feature=youtu.be\">Acesse o link<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>TV Tarob\u00e1<\/p>\n<p>Programa Vitrine Revista com Lu Oliveira<\/p>\n<p>24\u00a0de outubro de 2016<\/p>\n<p>Mitos e verdades sobre celulite<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=JbLiTIj8vIc&amp;feature=youtu.be\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg\" alt=\"zdj3dpvu\" width=\"139\" height=\"139\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/zdJ3dpVu.jpg 500w\" sizes=\"auto, (max-width: 139px) 100vw, 139px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=JbLiTIj8vIc&amp;feature=youtu.be\">Acesse o link<\/a><\/p>\n<hr \/>\n<p>Folha de Londrina &#8211; Social &#8211; Thiago Nassif<\/p>\n<p>17 de outubro de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4294\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-27102016-300x159.jpg\" alt=\"folha-de-londrina-27102016\" width=\"300\" height=\"159\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-27102016-300x159.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-27102016-800x423.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Folha-de-Londrina-27102016.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<hr \/>\n<p>Folha de Londrina &#8211; Social &#8211; Thiago Nassif<\/p>\n<p>01 de setembro de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4248\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-01092016-300x179.jpg\" alt=\"Thiago 01092016\" width=\"300\" height=\"179\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-01092016-300x179.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-01092016-800x477.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-01092016.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<hr \/>\n<p>Folha de Londrina &#8211; Social &#8211; Thiago Nassif<\/p>\n<p>06 de Agosto de 2016<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4247\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-06082016-300x188.jpg\" alt=\"Thiago 06082016\" width=\"300\" height=\"188\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-06082016-300x188.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-06082016-800x502.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2016\/07\/Thiago-06082016.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><strong>RPCTV &#8211; Rede Globo Londrina<\/strong><\/p>\n<p>27 de agosto de 2016 &#8211;\u00a0Inverno tamb\u00e9m \u00e9 \u00e9poca de cuidar da pele<\/p>\n<p><a href=\"https:\/\/g1.globo.com\/pr\/parana\/paranatv-2edicao\/videos\/t\/londrina\/v\/inverno-tambem-e-epoca-de-cuidar-da-pele\/5201169\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4225\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/10\/gdCnHsYD_400x400.jpg\" alt=\"gdCnHsYD_400x400\" width=\"80\" height=\"80\" \/><\/a><\/p>\n<p><a href=\"https:\/\/g1.globo.com\/pr\/parana\/paranatv-2edicao\/videos\/t\/londrina\/v\/inverno-tambem-e-epoca-de-cuidar-da-pele\/5201169\/\" target=\"_blank\">Acesse o video<\/a><\/p>\n<hr \/>\n<p><strong>Folha de Londrina<\/strong><\/p>\n<p>Coluna Social Thiago Nassif<\/p>\n<p>20 de junho de 2016<\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-Thiago-20062016a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4223\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-Thiago-20062016a-300x217.jpg\" alt=\"Folha - Thiago 20062016a\" width=\"300\" height=\"217\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-Thiago-20062016a-300x217.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-Thiago-20062016a-800x577.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-Thiago-20062016a.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><strong>Mar\u00e7o de 2016<\/strong><\/p>\n<p>Confira o v\u00eddeo na TV Record<\/p>\n<p>https:\/\/pr.ricmais.com.br\/\/ver-mais-londrina\/videos\/preenchimento-labial-esta-ganhando-fama-e-adeptos\/<\/p>\n<hr \/>\n<p>Novembro 2015 &#8211; Campanha de combate ao c\u00e2ncer de pele<\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/cAMPANHA.jpg\" rel=\"attachment wp-att-4045\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4045\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/cAMPANHA-212x300.jpg\" alt=\"cAMPANHA\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/cAMPANHA-212x300.jpg 212w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/cAMPANHA.jpg 723w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a> <a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0511-FOLHA-AGENDA.jpg\" rel=\"attachment wp-att-4046\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4046\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0511-FOLHA-AGENDA-300x263.jpg\" alt=\"0511 FOLHA AGENDA\" width=\"300\" height=\"263\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0511-FOLHA-AGENDA-300x263.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0511-FOLHA-AGENDA.jpg 791w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0911-folha-de-lda.jpg\" rel=\"attachment wp-att-4047\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4047\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0911-folha-de-lda-210x300.jpg\" alt=\"0911 folha de lda\" width=\"210\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0911-folha-de-lda-210x300.jpg 210w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/0911-folha-de-lda.jpg 718w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a> <a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/JL-0211.jpg\" rel=\"attachment wp-att-4048\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4048\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/JL-0211-73x300.jpg\" alt=\"JL 0211\" width=\"73\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/JL-0211-73x300.jpg 73w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/JL-0211.jpg 250w\" sizes=\"auto, (max-width: 73px) 100vw, 73px\" \/><\/a><\/p>\n<hr \/>\n<p><strong>TELEVIS\u00c3O<\/strong><\/p>\n<div><strong>VIVO GLOBO 06\/11<\/strong><\/div>\n<div><a href=\"https:\/\/g1.globo.com\/pr\/parana\/paranatv-1edicao\/videos\/t\/londrina\/v\/hc-faz-mutirao-de-prevencao-do-cancer-de-pele\/4590525\/\" target=\"_blank\">https:\/\/g1.globo.com\/pr\/parana\/paranatv-1edicao\/videos\/t\/londrina\/v\/hc-faz-mutirao-de-prevencao-do-cancer-de-pele\/4590525\/<\/a><\/div>\n<div><\/div>\n<div><strong>MAT\u00c9RIA DIA 7\/11<\/strong><\/div>\n<div><a href=\"https:\/\/g1.globo.com\/pr\/parana\/paranatv-1edicao\/videos\/t\/londrina\/v\/comeca-o-mutirao-contra-o-cancer-de-pele-no-hospital-de-clinicas\/4592655\/\" target=\"_blank\">https:\/\/g1.globo.com\/pr\/parana\/paranatv-1edicao\/videos\/t\/londrina\/v\/comeca-o-mutirao-contra-o-cancer-de-pele-no-hospital-de-clinicas\/4592655\/<\/a><\/div>\n<div><\/div>\n<div><strong>\u00a0TAROB\u00c1<\/strong><\/div>\n<div><a href=\"https:\/\/www.tvtaroba.com.br\/londrina\/jornaltarobaprimeiraedicao\/60293\/1r7atTOvLGc\" target=\"_blank\">https:\/\/www.tvtaroba.com.br\/londrina\/jornaltarobaprimeiraedicao\/60293\/1r7atTOvLGc<\/a><\/div>\n<div><\/div>\n<div>\n<hr \/>\n<\/div>\n<p>IMPRESSO<\/p>\n<p>Assessoria de Imprensa<\/p>\n<p>Folha de Londrina 24\/10\/2015<\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Boston2-Folha-24102015.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3943\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Boston2-Folha-24102015-220x300.jpg\" alt=\"Boston2 - Folha 24102015\" width=\"220\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Boston2-Folha-24102015-220x300.jpg 220w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Boston2-Folha-24102015.jpg 483w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/p>\n<hr \/>\n<p><strong>Setembro de 2015<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/25092015-FOLHA-Thiago.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4215\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/25092015-FOLHA-Thiago-184x300.jpg\" alt=\"25092015 - FOLHA Thiago\" width=\"184\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/25092015-FOLHA-Thiago-184x300.jpg 184w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/25092015-FOLHA-Thiago.jpg 628w\" sizes=\"auto, (max-width: 184px) 100vw, 184px\" \/><\/a><\/p>\n<hr \/>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#sc_gallery-5832 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-5832 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 24.99%;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-5832 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-5832 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see sc_gallery() in functions\/theme-shortcodes.php *\/\n\t\t\t<\/style>\n\t\t<div id='sc_gallery-5832' class='gallery element_classes galleryid-3850 gallery-columns-4 gallery-size-thumbnail file'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-1506-Cidades2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-1506-Cidades2-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-1506-Cidades.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Folha-1506-Cidades-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2907-Folha-Thiago.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2907-Folha-Thiago-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2907-Folha-Thiago-300x300.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2907-Folha-Thiago-800x800.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2207-JL.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2207-JL-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#sc_gallery-1239 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-1239 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33.33%;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-1239 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-1239 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see sc_gallery() in functions\/theme-shortcodes.php *\/\n\t\t\t<\/style>\n\t\t<div id='sc_gallery-1239' class='gallery element_classes galleryid-3850 gallery-columns-3 gallery-size-thumbnail file'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Clipping-Folha-da-Sexta-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Clipping-Folha-da-Sexta-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Clipping-Folha-da-Sexta-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/Clipping-Folha-da-Sexta-2-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p><strong>JUNHO 2015<\/strong><\/p>\n<p><a href=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2207-JL-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4216\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2207-JL-1-117x300.jpg\" alt=\"2207 JL\" width=\"117\" height=\"300\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2207-JL-1-117x300.jpg 117w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/09\/2207-JL-1.jpg 399w\" sizes=\"auto, (max-width: 117px) 100vw, 117px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Folha de Londrina segunda-feira, 2\u00a0de mar\u00e7o de 2017 Folha de Londrina segunda-feira, 5 de dezembro de 2016 Calv\u00edcie feminina precisa ser tratada precocemente Calv\u00edcie feminina precisa<span class=\"excerpt-hellip\"> [?]<\/span><\/p>\n","protected":false},"author":111,"featured_media":4237,"menu_order":22,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[159,174],"portfolio-types":[209],"class_list":["post-3850","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","category-clientes","category-instituto-pontello","portfolio-types-saude-medicina-2"],"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/portfolio\/3850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=3850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/4237"}],"wp:attachment":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media?parent=3850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/categories?post=3850"},{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/portfolio-types?post=3850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}