{"id":3641,"date":"2015-06-29T21:42:11","date_gmt":"2015-06-30T00:42:11","guid":{"rendered":"https:\/\/inovelondrina.web2145.uni5.net\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768.jpg"},"modified":"2015-06-29T21:42:11","modified_gmt":"2015-06-30T00:42:11","slug":"brazilian-166-1024x768","status":"inherit","type":"attachment","link":"https:\/\/www.inovelondrina.com.br\/agencia\/comunicacao-em-londrina\/lancamento-de-campanha\/brazilian-166-1024x768\/","title":{"rendered":"Brazilian 166 [1024&#215;768]"},"author":111,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-3641","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-200x300.jpg 200w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768.jpg 683w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":683,"height":1024,"file":"2015\/06\/Brazilian-166-1024x768.jpg","filesize":217944,"sizes":{"woocommerce_thumbnail":{"file":"Brazilian-166-1024x768-683x800.jpg","width":683,"height":800,"filesize":152528,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-683x800.jpg"},"woocommerce_gallery_thumbnail":{"file":"Brazilian-166-1024x768-300x300.jpg","width":300,"height":300,"filesize":33850,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-300x300.jpg"},"thumbnail":{"file":"Brazilian-166-1024x768-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-300x300.jpg"},"medium":{"file":"Brazilian-166-1024x768-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-200x300.jpg"},"large":{"file":"Brazilian-166-1024x768-683x1024.jpg","width":683,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768-683x1024.jpg"},"full":{"file":"Brazilian-166-1024x768.jpg","width":683,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon EOS 5D Mark II","caption":"","created_timestamp":"1307207093","copyright":"","focal_length":"24","iso":"2000","shutter_speed":"0.01","title":"","orientation":"0","keywords":[]}},"post":3632,"source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-166-1024x768.jpg","filename":"Brazilian-166-1024x768.jpg","filesize":217944,"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/3641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=3641"}],"wp:attached-to":[{"embeddable":true,"post_type":"portfolio","id":3632,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/portfolio\/3632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}