{"id":3640,"date":"2015-06-29T21:42:05","date_gmt":"2015-06-30T00:42:05","guid":{"rendered":"https:\/\/inovelondrina.web2145.uni5.net\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768.jpg"},"modified":"2015-06-29T21:42:05","modified_gmt":"2015-06-30T00:42:05","slug":"brazilian-165-1024x768","status":"inherit","type":"attachment","link":"https:\/\/www.inovelondrina.com.br\/agencia\/comunicacao-em-londrina\/lancamento-de-campanha\/brazilian-165-1024x768\/","title":{"rendered":"Brazilian 165 [1024&#215;768]"},"author":111,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-3640","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-300x200.jpg 300w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-800x534.jpg 800w, https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":683,"file":"2015\/06\/Brazilian-165-1024x768.jpg","filesize":199228,"sizes":{"woocommerce_thumbnail":{"file":"Brazilian-165-1024x768-800x683.jpg","width":800,"height":683,"filesize":134742,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-800x683.jpg"},"woocommerce_gallery_thumbnail":{"file":"Brazilian-165-1024x768-300x300.jpg","width":300,"height":300,"filesize":31961,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-300x300.jpg"},"woocommerce_single":{"file":"Brazilian-165-1024x768-800x534.jpg","width":800,"height":534,"filesize":97537,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-800x534.jpg"},"thumbnail":{"file":"Brazilian-165-1024x768-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-300x300.jpg"},"medium":{"file":"Brazilian-165-1024x768-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-300x200.jpg"},"large":{"file":"Brazilian-165-1024x768-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768-1024x683.jpg"},"full":{"file":"Brazilian-165-1024x768.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon EOS 5D Mark II","caption":"","created_timestamp":"1307207066","copyright":"","focal_length":"24","iso":"2000","shutter_speed":"0.0166666666667","title":"","orientation":"0","keywords":[]}},"post":3632,"source_url":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-content\/uploads\/2015\/06\/Brazilian-165-1024x768.jpg","filename":"Brazilian-165-1024x768.jpg","filesize":199228,"_links":{"self":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media\/3640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/comments?post=3640"}],"wp:attached-to":[{"embeddable":true,"post_type":"portfolio","id":3632,"href":"https:\/\/www.inovelondrina.com.br\/agencia\/wp-json\/wp\/v2\/portfolio\/3632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}